{"id":166232,"date":"2022-03-23T06:51:24","date_gmt":"2022-03-23T05:51:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/corigliano-entra-armato-di-coltello-e-rapina-una-parafarmacia\/"},"modified":"2023-01-16T17:02:14","modified_gmt":"2023-01-16T16:02:14","slug":"448970-corigliano-entra-armato-di-coltello-e-rapina-una-parafarmacia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/448970-corigliano-entra-armato-di-coltello-e-rapina-una-parafarmacia\/","title":{"rendered":"Corigliano, entra armato di coltello e rapina una parafarmacia"},"content":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; Rapina a mano armata ieri sera, poco prima della chiusura, ai danni di un&#8217;attivit\u00e0 di parafarmacia situata lungo Via Provinciale nell\u2019area urbana di Corigliano. Secondo i primi accertamenti una persona, con il <strong>volto coperto dalla mascherina<\/strong> \u00e8 entrata nella parafarmacia e minacciando con un coltello la persona che si trovava alla cassa, ha intimato la consegna dell\u2019intero incasso.<strong> Poi il rapinatore si \u00e8 dileguato<\/strong>. Sul posto sono poi arrivati i carabinieri i Corigliano Rossano che hanno avviato le indagini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; caccia al rapinatore a Corigliano Rossano dopo il colpo ai danni di una parafarmacia di via Provinciale<\/p>\n","protected":false},"author":42,"featured_media":166233,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-166232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=166232"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/166233"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=166232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=166232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=166232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}