{"id":166487,"date":"2022-03-27T08:01:47","date_gmt":"2022-03-27T06:01:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/inchiesta-mascherine-irregolari-lex-commissario-arcuri-a-rischio-processo\/"},"modified":"2023-01-16T17:02:31","modified_gmt":"2023-01-16T16:02:31","slug":"449559-inchiesta-mascherine-irregolari-lex-commissario-arcuri-a-rischio-processo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/449559-inchiesta-mascherine-irregolari-lex-commissario-arcuri-a-rischio-processo\/","title":{"rendered":"Inchiesta mascherine irregolari, l&#8217;ex commissario Arcuri a rischio processo"},"content":{"rendered":"<p>ROMA &#8211; <strong>Rischio processo<\/strong> per l&#8217;ex commissario straordinario per l&#8217;emergenza Covid, <strong>Domenico Arcuri.<\/strong> La Procura di Roma ha chiuso le indagini <strong>dell&#8217;inchiesta sull&#8217;acquisto di oltre 800 milioni di mascherine ritenute non conformi.<\/strong> Oltre ad Arcuri, <strong>accusato di abuso d&#8217;ufficio, i pm hanno notificato l&#8217;avviso di chiusura indagini ad altre 10 persone<\/strong> tra cui l&#8217;imprenditore Mario Benotti, cui \u00e8 contestato il traffico di influenze illecite, e Antonio Fabbrocini, responsabile unico del procedimento per la struttura commissariale accusato di frode nelle pubbliche forniture, falso e abuso d&#8217;ufficio.<\/p>\n<p>Ad Arcuri i magistrati di piazzale Clodio contestano di avere nella &#8220;qualit\u00e0 di pubblico ufficiale &#8211; \u00e8 detto nel capo di imputazione &#8211; <strong>e in concorso con Fabbrocini e in unione e concorso per mutuo accordo con l&#8217;imprenditore Vincenzo Tommasi<\/strong>&#8221; costituito &#8220;intenzionalmente, in capo al Tommasi, con ci\u00f2 abusando del loro ufficio, un&#8217;illecita posizione di vantaggio patrimoniale&#8221;.<strong> Un modus operandi che garantiva all&#8217;imprenditore &#8220;la facolt\u00e0 di avere rapporto commerciale con la Pa senza assumere alcuna responsabilit\u00e0 sul risultato della propria azione<\/strong> e sulla validit\u00e0 delle forniture che procurava; la quasi totale esclusiva nella intermediazione di fatto delle forniture di mascherine chirurgiche e dpi importati dalla Cina&#8221;.<\/p>\n<p>Per quanto riguarda la posizione di<strong> Benotti, accusato con altri sette di traffico di influenze, avrebbe sfruttato le &#8220;relazioni personali e occulte con Arcuri, ottenendo che quest&#8217;ultimo assicurasse ai partner di Benotti un&#8217;esclusiva in via di fatto nell&#8217;intermediazione delle forniture di maschere<\/strong> chirurgiche e dispositivi di protezione individuali&#8221;. Nei confronti di Fabbrocini si contesta, per quanto riguarda l&#8217;accusa di falso, di avere agito &#8220;nella qualit\u00e0 di rup&#8221; inducendo &#8220;il Cts ad attestare falsamente la conformita&#8217; dei presidi sanitari importati alle norme Uni En&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Procura ha chiuso le indagini dell&#8217;inchiesta sull&#8217;acquisto di oltre 800 milioni di dispositivi di protezione ritenuti non conformi<\/p>\n","protected":false},"author":61,"featured_media":166488,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-166487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=166487"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/166488"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=166487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=166487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=166487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}