{"id":166657,"date":"2022-03-30T09:17:50","date_gmt":"2022-03-30T07:17:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/nuovo-sbarco-di-migranti-62-persone-arrivate-su-barca-a-vela\/"},"modified":"2023-01-16T17:02:42","modified_gmt":"2023-01-16T16:02:42","slug":"449960-nuovo-sbarco-di-migranti-62-persone-arrivate-su-barca-a-vela","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/449960-nuovo-sbarco-di-migranti-62-persone-arrivate-su-barca-a-vela\/","title":{"rendered":"Nuovo sbarco di migranti, 62 persone arrivate su barca a vela"},"content":{"rendered":"<p>ROCCELLA IONICA (RC) &#8211; Poco prima dell&#8217;alba nel Porto di Roccella Ionica, sono approdati 62 migranti di nazionalit\u00e0 <strong>iraniana e afgana<\/strong>. Tra di loro anche 10 donne, di cui due in stato interessante, e sette bambini. A coordinare le operazioni di soccorso in mare da parte della Guardia Costiera, rese difficoltose a causa delle cattive condizioni meteo-marine, \u00e8 stata la sala operativa della capitaneria di Porto di Reggio Calabria.<\/p>\n<p>I profughi erano a bordo di una barca a vela di circa 20 metri in balia del mare mosso localizzata ad oltre 20 miglia dalla costa della Locride dai militari della motovedetta CP 322 della Guardia Costiera di Roccella Ionica. Dalle prime verifiche effettuate sembrerebbe che l&#8217;imbarcazione sia partita circa una settimana fa dalle coste della Turchia. Dopo lo sbarco, i <strong>62 migranti sono stati sottoposti al test del tampone molecolare<\/strong> da parte del personale specializzato dell&#8217;Azienda sanitaria provinciale di Reggio Calabria.<\/p>\n<p>Successivamente, su disposizione della Prefettura reggina, sono stati momentaneamente sistemati nella tensostruttura realizzata all&#8217;interno del Porto e gestita dai volontari della Croce Rossa e della Protezione Civile. L&#8217;arrivo di oggi si configura come il sesto sbarco di migranti nel Porto di Roccella in questi primi tre mesi del 2022. Appena due settimane fa erano giunti altri 104 profughi di nazionalit\u00e0 egiziana e siriana. L&#8217;anno scorso solo nella struttura portuale roccellese si sono <strong>verificati 49 arrivi dei 55 sbarchi<\/strong> avvenuti nella costa ionica della Locride, per un totale di oltre 6 mila migranti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra i migranti di nazionalit\u00e0 iraniana e afgana ci sono anche dieci donne, di cui due incinte, e sette bambini<\/p>\n","protected":false},"author":42,"featured_media":166658,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-166657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=166657"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/166658"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=166657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=166657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=166657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}