{"id":166677,"date":"2022-03-30T13:36:54","date_gmt":"2022-03-30T11:36:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-droga-e-presunti-pusher-nel-centro-storico-cinque-condanne-e-tre-assoluzioni\/"},"modified":"2023-01-16T17:02:43","modified_gmt":"2023-01-16T16:02:43","slug":"450002-cosenza-droga-e-presunti-pusher-nel-centro-storico-cinque-condanne-e-tre-assoluzioni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/450002-cosenza-droga-e-presunti-pusher-nel-centro-storico-cinque-condanne-e-tre-assoluzioni\/","title":{"rendered":"Cosenza, droga e presunti pusher nel centro storico. Cinque condanne e tre assoluzioni"},"content":{"rendered":"<p>COSENZA &#8211; Il Gup del Tribunale di Cosenza, Letizia Benigno, ha emesso sentenza sull&#8217;inchiesta della Procura di Cosenza nei confronti di<strong> 8 indagati accusati di cessione di sostanze stupefacenti e reati di estorsione aggravata e violenza privata<\/strong>. Nell&#8217;inchiesta della Procura, portata a termine dagli agenti della Squadra mobile della Questura di Cosenza e della locale Sezione di Polizia giudiziaria e del Reparto Prevenzione Crimine \u201cCalabria Settentrionale\u201d il presunto gruppo gestiva la distribuzione di sostanze stupefacenti nel centro storico della citt\u00e0 (hashish e cocaina) in particolare su Corso Umberto, Via Rivocati e zone limitrofe. In alcuni casi, tramite attivit\u00e0 capativa e sistemi di videosorveglianza, erano state cristallizzare dagli inquirenti cessioni nei pressi di un istituto scolastico, oltre a diversi episodi di minacce per ottenere i soldi dello stupefacente. Nel corso delle indagini erano state<strong> sequestrate sostanze stupefacenti, appunti vari ed un assegno bancario<\/strong>. Le indagini nascevano dagli sviluppi di altra attivit\u00e0 investigativa che aveva portato all\u2019adozione di otto ordinanze di misure cautelari.<\/p>\n<h4>Condanne e assoluzioni<\/h4>\n<p>Oggi sono arrivate 5 condanne per <strong>Alfredo Sirufo<\/strong> (4 anni e otto mesi e pagamento di una multa di 3.600 euro e difeso dall\u2019<strong>avvocato Antonio Ingrosso<\/strong>), <strong>Candido Perri<\/strong> (3 anni e 3 mesi e pagamento di 2.000 euro di multa difes\u00a0dall\u2019a<strong>vvocato Giampiero Calabrese<\/strong>), <strong>Daniele Morrone <\/strong>(un anno di reclusione e pagamento di una multa di 2.000 euro), <strong>Iliyan Cvetanov<\/strong> (un anno e due mesi e pagamento di una multa di 2.000 euro)\u00a0e infine <strong>Carmine Ariello<\/strong> (1 anno e 3 mesi di reclusione). Assolti &#8220;perch\u00e9 il fatto non sussiste&#8221; da tutte le imputazioni contestate Andrea Ciancio, Pietro De Mari e Livio Sirufo mentre Carla Greco e Giuseppe Muto sono stati rinviati a giudizio. Nel collegio difensivo figurano gli avvocati Fabio Parise, Rossana Cribari, Amelia Ferrari, Giuseppe Lanzino, Domenico Caputo e Gabriele Volpe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;inchiesta della Procura su un presunto gruppo gestiva la distribuzione di sostanze stupefacenti nel centro storico della citt\u00e0<\/p>\n","protected":false},"author":55,"featured_media":166678,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-166677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=166677"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/166678"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=166677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=166677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=166677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}