{"id":166719,"date":"2022-03-31T08:57:07","date_gmt":"2022-03-31T06:57:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/loizzo-a-la-regina-pronto-soccorso-trebisacce-rischia-di-chiudere-intervenire-subito\/"},"modified":"2023-01-16T17:02:46","modified_gmt":"2023-01-16T16:02:46","slug":"450146-loizzo-a-la-regina-pronto-soccorso-trebisacce-rischia-di-chiudere-intervenire-subito","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/450146-loizzo-a-la-regina-pronto-soccorso-trebisacce-rischia-di-chiudere-intervenire-subito\/","title":{"rendered":"Loizzo a La Regina :&#8221;pronto soccorso Trebisacce rischia di chiudere. Intervenire subito&#8221;"},"content":{"rendered":"<p>TREBISACCE (CS) &#8211; &#8220;Il pronto soccorso dell&#8217;<strong>ospedale di Trebisacce<\/strong> \u00e8 senza personale medico e rischia di interrompere <strong>i servizi in mancanza di un intervento risolutivo<\/strong> da parte dell&#8217;Asp di Cosenza&#8221;. Lo afferma in una nota<strong> Simona Loizzo,<\/strong> capogruppo della Lega in consiglio regionale.<\/p>\n<p>&#8220;Dal giugno del 2020 &#8211; dice Loizzo &#8211;<strong> i sanitari del nosocomio chiedono inutilmente un intervento dell&#8217;azienda sanitaria provinciale<\/strong> e in questi giorni hanno ribadito al commissario La Regina la necessit\u00e0 di non perdere tempo. Mancano anche gli anestesisti &#8211; aggiunge Loizzo &#8211; e in queste condizioni <strong>\u00e8 impossibile portare avanti il lavoro.<\/strong> Mi auguro che La Regina voglia intervenire tempestivamente &#8211; conclude la Loizzo &#8211; per evitare la sospensione di un servizio vitale per tutto il comprensorio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;I sanitari del nosocomio da giugno chiedono inutilmente un intervento dell&#8217;azienda sanitaria provinciale ribadendo la necessit\u00e0 di non perdere tempo&#8221;<\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-166719","post","type-post","status-publish","format-standard","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=166719"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166719\/revisions"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=166719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=166719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=166719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}