{"id":166727,"date":"2022-03-31T11:02:23","date_gmt":"2022-03-31T09:02:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/i-soldi-della-droga-riciclati-sequestrati-beni-per-7-milioni-ad-una-58enne\/"},"modified":"2023-01-16T17:02:47","modified_gmt":"2023-01-16T16:02:47","slug":"450173-i-soldi-della-droga-riciclati-sequestrati-beni-per-7-milioni-ad-una-58enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/450173-i-soldi-della-droga-riciclati-sequestrati-beni-per-7-milioni-ad-una-58enne\/","title":{"rendered":"I soldi della droga riciclati, sequestrati beni per 7 milioni ad una 58enne"},"content":{"rendered":"<p>GENOVA &#8211; I carabinieri del nucleo investigativo di La Spezia hanno eseguito un decreto di sequestro preventivo nei confronti di una donna di 58 anni, originaria della provincia di Crotone, relativo a beni mobili e immobili individuati in Italia ed all&#8217;estero per un valore di circa 7 mln di euro. Le indagini erano nate dalle dichiarazioni di un collaboratore di giustizia che fece riferimento <strong>all&#8217;importazione dal Sudamerica di circa 800 chili di cocaina<\/strong> arrivati in porto a Spezia e stoccati in un <strong>garage del centro cittadino<\/strong>.<\/p>\n<p>Era agosto 2012: dopo poche settimane nel crotonese uno dei soggetti coinvolti nell&#8217;importazione della cocaina \u00e8 stato ucciso con 4 colpi di pistola alla testa. Dopo l&#8217;omicidio, i Carabinieri spezzini hanno avviato indagini a carico della sorella del morto, residente a Spezia. La donna \u00e8 stata indagata anche per<strong> riciclaggio delle somme ricavate dalla vendita della droga<\/strong>, soldi che aveva usato per acquistare beni immobili, quote societarie, diamanti, gioielli, quadri. Parte delle somme sarebbe in parte finita su conti correnti bancari nazionali ed esteri aperti ad hoc e parte occultata in cassette di sicurezza o reimpiegata in attivit\u00e0 economiche, finanziarie, imprenditoriali e speculative in Svizzera, Romania, Capo Verde, Sao Tome e Principe e Spagna.<\/p>\n<p><strong>Gli investigatori hanno quantificato in almeno 7 milioni di euro le cifre movimentate<\/strong>. Il patrimonio sequestrato \u00e8 da aggiungere a quello gi\u00e0 confiscato a fine 2020 a un intermediario finanziario residente in Svizzera e originario della provincia della Spezia, condannato a luglio, a seguito di patteggiamento, a due anni di detenzione e alla confisca dell&#8217;intero patrimonio. L&#8217;uomo, ritenuto il cassiere dell&#8217;indagata e del fratello ucciso aveva costituito una societ\u00e0 offshore in Belize, aprendo attraverso essa anche conti bancari a Lugano. Alla fine di febbraio 2022 il Tribunale di Genova ha emesso rogatoria finalizzata alla confisca dei saldi sui conti correnti bancari accesi su banche private di Lugano, di una villa sul lago di Lugano e ad altre forme di investimento per valore stimato in circa 9 mln di euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gioielli, societ\u00e0 e appartamenti sequestrati dai carabinieri sono ritenuti il provento della vendita di 800 chili di cocaina<\/p>\n","protected":false},"author":42,"featured_media":166728,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-166727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=166727"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/166728"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=166727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=166727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=166727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}