{"id":166771,"date":"2022-04-01T04:54:07","date_gmt":"2022-04-01T02:54:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/lite-fra-vicini-davanti-ad-una-casa-popolare-un-ferito\/"},"modified":"2023-01-16T17:02:50","modified_gmt":"2023-01-16T16:02:50","slug":"450290-lite-fra-vicini-davanti-ad-una-casa-popolare-un-ferito","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/450290-lite-fra-vicini-davanti-ad-una-casa-popolare-un-ferito\/","title":{"rendered":"Lite fra vicini davanti ad una casa popolare, un ferito"},"content":{"rendered":"<p>LIMBADI (VV) &#8211; Una lite tra vicini di casa \u00e8 culminata a colpi di pistola. E&#8217; accaduto a Limbadi, nel Vibonese, dove un cittadino di nazionalit\u00e0 romena di 43 anni, \u00e8 stato ferito dinanzi a una casa popolare. I carabinieri hanno gi\u00e0 fermato un uomo di 67 anni di Limbadi, accusato di aver sparato. Il 43enne ferito \u00e8 stato trasportato con un\u2019auto all\u2019ospedale di Vibo Valentia dove \u00e8 giunto in codice rosso al Pronto soccorso. L&#8217;uomo \u00e8 ricoverato in prognosi riservata. Sul luogo della sparatoria \u00e8 arrivata anche la polizia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La persona ferita dai colpi di pistola \u00e8 ricoverata in prognosi riservata. Sul luogo della sparatoria carabinieri e polizia<\/p>\n","protected":false},"author":42,"featured_media":166772,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-166771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=166771"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/166771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/166772"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=166771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=166771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=166771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}