{"id":16696,"date":"2013-01-29T08:41:32","date_gmt":"2013-01-29T07:41:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=16696"},"modified":"2023-01-17T13:14:45","modified_gmt":"2023-01-17T12:14:45","slug":"5791-porto-di-gioia-tauro-sequestrati-110-kg-di-cocaina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/5791-porto-di-gioia-tauro-sequestrati-110-kg-di-cocaina\/","title":{"rendered":"Porto di Gioia Tauro: sequestrati 110 Kg di cocaina"},"content":{"rendered":"<p><strong>GIOIA TAURO<\/strong> &#8211;&nbsp;L&#8217;operazione, condotta dalla Direzione Distrettuale Antimafia di Reggio Calabria, in stretto e costante coordinamento con la Procura della<\/p>\n<p>  <!--more-->  <\/p>\n<p>Repubblica di Palmi, s&#8217;inquadra nell&#8217;ambito di una piu&#8217; vasta attivita&#8217; di polizia giudiziaria che ha consentito, dopo una serie di incroci documentali e successivi meticolosi controlli eseguiti su numerosi container in transito presso il porto di Gioia Tauro, realizzati anche attraverso l&#8217;impiego di apparecchiature scanner in uso alla Dogana, di individuare l&#8217;illecito carico di droga proveniente dal Cile. La merce avrebbe fruttato, con la vendita al dettaglio, oltre 25 milioni di euro. I sospetti degli investigatori sono sorti dalla comparazione tra la documentazione doganale e le caratteristiche fisiche del carico, costituito da &#8220;sacchi di lupini&#8221;. All&#8217;esito dei controlli eseguiti, i Finanzieri ed i Funzionari della Dogana di Gioia Tauro hanno contato, all&#8217;interno di 4 borsoni abilmente occultati nel carico, 100 panetti di droga, per un peso complessivo di circa 110 chili di cocaina di elevata qualita&#8217; e purezza. L&#8217;operazione odierna conferma che il porto di Gioia Tauro \u00e8 uno snodo centrale nelle rotte dei traffici illeciti di sostanze stupefacenti provenienti dal Sud America. A tal proposito, nel 2012, e&#8217; stato sottoposto a sequestro un quantitativo complessivo di droga pari a oltre 2100 chili di cocaina, che si aggiungono alla tonnellata sottoposta a sequestro nel corso dell&#8217;anno 2011<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GIOIA TAURO &#8211;&nbsp;L&#8217;operazione, condotta dalla Direzione Distrettuale Antimafia di Reggio Calabria, in stretto e costante coordinamento con la Procura della<\/p>\n","protected":false},"author":22,"featured_media":16697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-16696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=16696"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/16697"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=16696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=16696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=16696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}