{"id":167032,"date":"2022-04-05T15:32:58","date_gmt":"2022-04-05T13:32:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-cade-da-un-ponteggio-in-un-cantiere-edile-grave-un-operaio-di-50-anni\/"},"modified":"2023-01-16T17:03:07","modified_gmt":"2023-01-16T16:03:07","slug":"450897-rende-cade-da-un-ponteggio-in-un-cantiere-edile-grave-un-operaio-di-50-anni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/450897-rende-cade-da-un-ponteggio-in-un-cantiere-edile-grave-un-operaio-di-50-anni\/","title":{"rendered":"Rende, cade da un ponteggio in un cantiere edile. Grave un operaio di 50 anni"},"content":{"rendered":"<p>RENDE &#8211; I carabinieri di Rende hanno <strong>posto sotto sequestro l&#8217;area di un cantiere edile<\/strong> in via Ungaretti dopo che questa mattina <strong>un operario, un 50enne, \u00e8 caduto da un ponteggio<\/strong> finendo rovinosamente al suolo dopo un volo di alcuni metri. L&#8217;uomo, subito soccorso dall&#8217;arrivo del 118, <strong>\u00e8 stato trasportato all&#8217;Annunziata di Cosenza dove si trova in prognosi riservata<\/strong>. Dell&#8217;accaduto sono stati informati i carabinieri che, agli ordini del capitano Maria Chiara Soldano, hanno avviato le indagini. Per questo il cantiere \u00e8 posto sotto sequestro ed \u00e8 stato effettuato anche un sopralluogo da parte de<b>i tecnici<\/b> che si occupano di sicurezza sul lavoro in servizio dello Spisal dell\u2019Asp di Cosenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri di Rende hanno posto sotto sequestro l&#8217;area dopo che un operaio \u00e8 caduto da un ponteggio finendo in ospedale<\/p>\n","protected":false},"author":55,"featured_media":167033,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-167032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/167032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=167032"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/167032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/167033"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=167032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=167032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=167032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}