{"id":167236,"date":"2022-04-08T14:00:15","date_gmt":"2022-04-08T12:00:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/mendicino-iniziati-gli-interventi-di-bitumazione-su-diverse-strade-secondarie\/"},"modified":"2023-01-16T17:03:21","modified_gmt":"2023-01-16T16:03:21","slug":"451384-mendicino-iniziati-gli-interventi-di-bitumazione-su-diverse-strade-secondarie","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/451384-mendicino-iniziati-gli-interventi-di-bitumazione-su-diverse-strade-secondarie\/","title":{"rendered":"Mendicino, iniziati gli interventi di bitumazione su diverse strade secondarie"},"content":{"rendered":"<p><span class=\"v1s2\">MENDICINO (CS) &#8211; &#8220;Oggi da <strong>Via Muoio Grande, a Contrada Rosario, da Via Ghandi, a Contrada Tivolille, e da Via Europa<\/strong>, la strada che collega Mendicino a Cosenza attraverso Serra Spiga, abbiamo iniziato una<strong> serie di interventi di bitumazione delle strade secondarie<\/strong> del nostro territorio. Ora <\/span>che le temperature lo consentono, come avevamo annunciato, siamo partiti con una serie di interventi sul territorio per riparare i tratti ammalorati dopo le piogge invernali. <strong>Ci sposteremo poi da Luned\u00ec su Via Acheruntia<\/strong>&#8220;. A darne comunicazione il Sindaco di Mendicino Antonio Palermo che ha parlato di un primo intervento.\u00a0Nelle prossime settimane, infatti, sar\u00e0 la volta di Via Alessandro il Molosso e Via Ferrera. &#8220;Continueremo per tutta la primavera e l&#8217;estate &#8211; ha spiegato il sindaco. Seguir\u00e0, infatti, <strong>un intervento ancora pi\u00f9 cospicuo gi\u00e0 approvato in Giunta<\/strong> che riguarder\u00e0 decine di strade secondarie, <strong>grazie ad un finanziamento di quasi 150.000 \u20ac&#8221;<\/strong>.<\/p>\n<p>&#8220;<strong>Era una richiesta di molti cittadini<\/strong> e come sempre con seriet\u00e0 e impegno appena e stato possibile siamo intervenuti con decisione e per la fine di questa stagione di bel tempo Mendicino avr\u00e0 gran parte delle sue strade secondarie ammodernate, bitumate e ben sistemate, come avvenuto negli anni scorsi per i quasi 10 km di strada principale. E da Sindaco sono orgoglioso di questo altro tassello importante per il miglioramento della nostra Citt\u00e0&#8221; ha concluso Palermo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presto un secondo pi\u00f9 cospicuo intervento su decine di strade secondarie, grazie ad un finanziamento di quasi 150.000 \u20ac<\/p>\n","protected":false},"author":55,"featured_media":167237,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-167236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/167236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=167236"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/167236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/167237"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=167236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=167236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=167236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}