{"id":167518,"date":"2022-04-13T08:13:31","date_gmt":"2022-04-13T06:13:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sette-chili-di-cocaina-dalla-calabria-in-sicilia-in-manette-un-uomo-e-una-donna\/"},"modified":"2023-01-16T17:03:39","modified_gmt":"2023-01-16T16:03:39","slug":"452006-sette-chili-di-cocaina-dalla-calabria-in-sicilia-in-manette-un-uomo-e-una-donna","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/452006-sette-chili-di-cocaina-dalla-calabria-in-sicilia-in-manette-un-uomo-e-una-donna\/","title":{"rendered":"Dalla Calabria in Sicilia con 7 chili di cocaina, in manette un uomo e una donna"},"content":{"rendered":"<p>MESSINA &#8211; Gli uomini della Guardia di finanza di Messina, con l\u2019ausilio dei cani antidroga Ghimly ed Haidy, hanno scoperto e sequestrato<strong> 7 chilogrammi di cocaina in transito dagli imbarchi di Messina<\/strong> e tratto in arresto <strong>due persone<\/strong>, un uomo straniero ed una <strong>donna di origini calabresi<\/strong>, ritenuti responsabili dell\u2019illecito traffico di narcotico. Le unit\u00e0 cinofile hanno ispezionato un&#8217;autovettura appena sbarcata dalla costa calabrese, nella quale sono stati trovati <strong>sei panetti di cocaina<\/strong> (di cui n. 2 riportanti il marchio di una nota casa di moda), per un peso complessivo pari a circa sette chilogrammi, trasportati all\u2019interno di un <strong>doppiofondo ricavato nel vano porta oggetti anteriore del mezzo.<\/strong><\/p>\n<p>Sulla base delle risultanze investigative, gli indagati sono stati tratti in arresto, in flagranza di reato, per traffico di sostanze stupefacenti. L\u2019uomo \u00e8 stato sottoposto a custodia cautelare in carcere, mentre la donna \u00e8 stata posta agli arresti domiciliari. La droga avrebbe potuto fruttare, sulle piazze di spaccio della provincia, oltre un milione e 800 mila euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La droga, nascosta in un doppiofondo ricavato nel vano porta oggetti anteriore del mezzo, avrebbe potuto fruttare, sulle piazze di spaccio oltre un milione e 800 mila euro<\/p>\n","protected":false},"author":42,"featured_media":167519,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-167518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/167518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=167518"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/167518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/167519"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=167518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=167518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=167518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}