{"id":167753,"date":"2022-04-17T08:09:28","date_gmt":"2022-04-17T06:09:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/de-cicco-in-7-10-giorni-tutte-le-buche-coperte-e-i-tratti-dissestati-rifatti-da-zero\/"},"modified":"2023-01-16T17:03:55","modified_gmt":"2023-01-16T16:03:55","slug":"452586-de-cicco-in-7-10-giorni-tutte-le-buche-coperte-e-i-tratti-dissestati-rifatti-da-zero","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/452586-de-cicco-in-7-10-giorni-tutte-le-buche-coperte-e-i-tratti-dissestati-rifatti-da-zero\/","title":{"rendered":"De Cicco &#8220;in 7-10 giorni tutte le buche coperte e i tratti dissestati rifatti da zero&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; La data di inizio degli <strong>interventi di rifacimento del manto stradale <\/strong>\u00e8 fissata per <a href=\"https:\/\/quicosenza.it\/news\/15015\" target=\"_blank\" rel=\"noopener\">mercoled\u00ec prossimo<\/a>. Una notizia attesa da migliaia di automobilisti cosentini, messi a dura prova ogni giorno dalle pessime condizioni di molti tratti di strada, diventati veri e colabrodo con buche e voragini un po&#8217; ovunque. Lavori programmati da tempo, ma che saranno attuati solo nei prossimi giorni perch\u00e9, aveva spiegato il Sindaco Caruso occorreva &#8220;<strong>attendere che le condizioni meteorologiche migliorassero<\/strong>, con un aumento delle temperature, per consentire la produzione del bitume a caldo che, come \u00e8 noto, pu\u00f2 avvenire solo con temperature esterne pi\u00f9 miti&#8221;.<\/p>\n<h4>Non solo coperture. Interventi su interi tratti di strada<\/h4>\n<p>E l&#8217;Assessore alla Manutenzione ordinaria e straordinaria delle strade<strong>, Francesco De Cicco,<\/strong> evidenzia come quelli dei prossimi giorni a Cosenza saranno <strong>interventi che non si limiteranno a coprire semplicemente le buche<\/strong>, ma <strong>verranno rifatti interi tratti di strada dissestati<\/strong> &#8220;iniziamo mercoled\u00ec con un piano di bitumazione &#8211; ha spigato de Cicco che<strong> partir\u00e0 dalle strade principali e pi\u00f9 percorribili <\/strong>dove andremo a fare un lavoro di pulitura, scarifica, emulsione, ricompattamento della sede stradale per poi effettuare la bitumazione. Faremo un intervento profondo su tute le strade principali e poi utilizzeremo le cooperative sociali anche <strong>nelle strade secondarie dove andremo a coprire tutte le buche<\/strong>&#8220;.<\/p>\n<h4>Rifatte tutte le strisce pedonali<\/h4>\n<p><strong>&#8220;In una settimana, massimo dieci giorni, andremo ad azzerare tutto quello che c&#8217;\u00e8 come buche e tratti di strada dissesti<\/strong>&#8221; ha spigato De Cicco aggiungendo che &#8220;sia successivamente ma anche contemporaneamente ai lavori sulle strade cittadine, partiremo con la nuova segnaletica verticale e orizzontale. <strong>Rifaremo anche tutte le triste pedonali della citt\u00e0 <\/strong>e la restante segnaletica orizzontale e verticale usurata o deteriorata dal tempo&#8221;.<\/p>\n<h4>Lavori sulla Fibra. Aziende dovranno ripristinare le strade<\/h4>\n<p>E sui ritardi negli interventi alle strade, De Cicco sottolinea che un altro motivo che ha portato allo slittamento, oltre a quello meteorologico, ha riguardato anche i lavori di realizzazione e messa in operare della Fibra ottica in citt\u00e0 &#8220;interventi da parte dei vari gestori &#8211; ha spiegato De Cicco &#8211; che <strong>hanno dissestato le strade molto pi\u00f9 rispetto agli altri anni<\/strong>. Abbiamo fatto una riunione insieme al Sindaco Caruso dove abbiamo convocato tutte le aziende e fatto un accordo:<strong> dove hanno lasciato scavi a met\u00e0 o bitumazione fatte male, dovranno intervenire e ripristinare<\/strong>. Inoltre, ci sar\u00e0 <b>un nucleo di controllo che si occuper\u00e0 di controllare che le ditte eseguano i lavori ad opera d&#8217;arte&#8221;.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Assessore De Cicco &#8220;non solo buche coperte ma interi tratti di strada rifatti. Un nucleo di controllo verificher\u00e0 che i lavori delle ditte siano fatti ad opera d&#8217;arte&#8221;<\/p>\n","protected":false},"author":23,"featured_media":167754,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19,135],"class_list":["post-167753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina","tag-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/167753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=167753"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/167753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/167754"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=167753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=167753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=167753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}