{"id":168069,"date":"2022-04-23T07:46:30","date_gmt":"2022-04-23T05:46:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/torch-run-la-fiaccola-della-speranza-fa-tappa-anche-in-calabria\/"},"modified":"2023-01-16T17:04:16","modified_gmt":"2023-01-16T16:04:16","slug":"453385-torch-run-la-fiaccola-della-speranza-fa-tappa-anche-in-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/453385-torch-run-la-fiaccola-della-speranza-fa-tappa-anche-in-calabria\/","title":{"rendered":"Torch Run, la Fiaccola della Speranza fa tappa anche in Calabria"},"content":{"rendered":"<p>CATANZARO &#8211; Anche la Calabria accoglie la <strong>\u201cFiaccola della Speranza\u201d<\/strong>. E si prepara a farlo in grande stile, attraverso la TORCH RUN promossa dall&#8217;associazione<strong> Special Olympics<\/strong>: una staffetta speciale, che avr\u00e0 per protagonisti atleti con disabilit\u00e0.<\/p>\n<p>Quest\u2019anno attorno alla bella iniziativa \u00e8 stato costruito un vero e proprio evento, grazie all&#8217;interessamento e alla sensibilit\u00e0 dimostrata dalla Regione Calabria per tramite della Vicepresidenza e della Protezione Civile.<\/p>\n<p>I dettagli della manifestazione socioculturale e sportiva saranno illustrati nel corso di <strong>una conferenza stampa che si terr\u00e0 marted\u00ec 26 aprile<\/strong>, alle ore 11.30, nella Sala Oro della Cittadella Regionale, a Catanzaro.<\/p>\n<p>All&#8217;incontro con la stampa, moderato dal conduttore Domenico Gareri, interverranno il Vicepresidente della Regione, Giusi Princi, il Direttore generale della Protezione Civile Calabria, Fortunato Varone, il Questore di Catanzaro, Maurizio Agricola, il Direttore regionale Special Olympics Team Calabria, Luisa Elitro, e il referente per la provincia catanzarese, Francesco Miscioscia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Promossa dall&#8217;associazione Special Olympics, \u00e8 una staffetta speciale che avr\u00e0 per protagonisti atleti con disabilit\u00e0<\/p>\n","protected":false},"author":58,"featured_media":168070,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-168069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=168069"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168069\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/168070"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=168069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=168069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=168069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}