{"id":168075,"date":"2022-04-23T09:29:43","date_gmt":"2022-04-23T07:29:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/occhiuto-esclude-ugl-dai-tavoli-romani-il-sindacato-protesta-solita-triade-nebulosa\/"},"modified":"2023-01-16T17:04:16","modified_gmt":"2023-01-16T16:04:16","slug":"453405-occhiuto-esclude-ugl-dai-tavoli-romani-il-sindacato-protesta-solita-triade-nebulosa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/453405-occhiuto-esclude-ugl-dai-tavoli-romani-il-sindacato-protesta-solita-triade-nebulosa\/","title":{"rendered":"Occhiuto esclude Ugl dai tavoli romani, il sindacato protesta &#8220;solita triade nebulosa&#8221;"},"content":{"rendered":"<p>CATANZARO &#8211; &#8220;Manifestiamo tutta la nostra inquietudine di fronte all&#8217;ennesimo tentativo di limitare la democrazia e il futuro della regione nell&#8217;ambito angusto di stanze del potere stantie e deleterie. L&#8217;incontro tenuto tra il vertice regionale e una parte delle forze sociali, nello specifico la &#8216;solita triade&#8217;, rappresenta in maniera palese il perseverare nella vecchia logica di limitare, negli ambiti di un potere ben definito e nebuloso, ogni prospettiva d&#8217;investimento che dovrebbe, invece, essere aperto a tutti i contributi proprio per il bene della nostra terra&#8221;. E&#8217; quanto si afferma in una nota dell&#8217;<strong>Ugl Calabria<\/strong>, che ha indetto lo stato di agitazione di tutte le categorie, in riferimento all&#8217;<strong><a href=\"https:\/\/quicosenza.it\/news\/15055\" target=\"_blank\" rel=\"noopener\">incontro a Roma tra il presidente Occhiuto e le segreterie nazionali di Cgil, Cisl e Uil<\/a><\/strong>.<\/p>\n<h4>&#8220;Siamo stati esclusi, abbiamo tanti progetti per la Calabria&#8221;<\/h4>\n<p>&#8220;\u00c8 persino imbarazzante &#8211; afferma <strong>Ornella Cuzzupi, segretario generale Ugl<\/strong> della Calabria &#8211; dover prendere atto che anche questa amministrazione intende la gestione della &#8216;res pubblica&#8217; come un fatto privato tale da potersi scegliere gli attori e gli interlocutori in modo dispotico e non secondo l&#8217;interesse della nostra terra. L&#8217;Ugl ha presentato a suo tempo, direttamente al presidente e alla vicepresidente della Regione, <strong>progetti e iniziative che avrebbero dato lustro e prospettiva al lavoro e al territorio<\/strong>, ma invece di rispondere e prendere atto di quanto proposto, si \u00e8 preferito rivolgere lo sguardo altrove coinvolgendo, in fumosi discorsi fatti di sola apparenza, chi della politica e del sindacato ne fa un uso strumentale per interessi propri e di parte&#8221;.<\/p>\n<h4>Ugl pretende &#8220;chiarezza nei rapporti&#8221;<\/h4>\n<p>L&#8217;Ugl Calabria, riporta la nota, &#8220;pretende la chiarezza nei rapporti e la trasparenza in ogni singolo aspetto legato alla gestione della Regione&#8221;. &#8220;Non accetteremo mai &#8211; sostiene ancora Cuzzupi &#8211; di<strong> prendere parte a sceneggiate senza concretezza<\/strong> e a convocazioni che sanno di copertura per altri fini. Lo abbiamo detto e lo ripeteremo sempre: vogliamo un progetto concreto, chiaro, trasparente e condiviso per la rinascita della nostra terra. Forse \u00e8 questo che fa paura. Noi abbiamo posto sul tappeto temi realistici ai quali occorre dare risposta. Lo abbiamo fatto in maniera chiara, leale e onesta. Di fronte a ci\u00f2, il presidente Occhiuto, ha preferito dar seguito a deleterie logiche politiche, forse decise da altre parti, piuttosto che <strong>affrontare il problema Calabria<\/strong> nella sua gravit\u00e0 ed urgenza&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cos\u00ec il segretario Ornella Cuzzupi dopo l&#8217;incontro avvenuto tra il Governatore e Cgil, Cisl e Uil. Indetto lo sciopero<\/p>\n","protected":false},"author":58,"featured_media":168076,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-168075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=168075"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/168076"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=168075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=168075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=168075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}