{"id":168087,"date":"2022-04-23T11:20:00","date_gmt":"2022-04-23T09:20:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tragedia-a-cetraro-travolto-dalla-motozappa-muore-71enne\/"},"modified":"2023-01-16T17:04:17","modified_gmt":"2023-01-16T16:04:17","slug":"453432-tragedia-a-cetraro-travolto-dalla-motozappa-muore-71enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/453432-tragedia-a-cetraro-travolto-dalla-motozappa-muore-71enne\/","title":{"rendered":"Tragedia a Cetraro: travolto dalla motozappa, muore 71enne"},"content":{"rendered":"<p>CETRARO (CS) &#8211; Ennesima tragedia sul lavoro nel cosentino. Un uomo \u00e8 morto a Cetraro schiacciato dal rimorchio della motozappa che stava conducendo. Si tratta <strong>Pino Nepita, 71enne in pensione<\/strong>. L\u2019incidente ieri sera attorno alle 21,30 mentre l\u2019uomo era intento a lavorare nel terreno di sua propriet\u00e0 in via Lungo Aron.\u00a0 Immediati i soccorsi per salvare l\u2019uomo ma che si sono rivelati vani. I medici del 118 giunti sul posto non hanno potuto far altro che constatare il decesso del 71enne. <strong>Sulla vicenda si \u00e8 aperta un\u2019inchiesta<\/strong> per comprendere l\u2019esatta dinamica dell&#8217;incidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel cosentino l&#8217;ennesimo caso di incidente mortale provocato da un mezzo agricolo. Sulla vicenda si \u00e8 aperta un\u2019inchiesta<\/p>\n","protected":false},"author":58,"featured_media":168088,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-168087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=168087"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/168088"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=168087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=168087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=168087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}