{"id":168117,"date":"2022-04-24T08:00:23","date_gmt":"2022-04-24T06:00:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sorpresi-a-sversare-materiale-edile-in-un-terreno-privato-cinque-persone-denunciate\/"},"modified":"2023-01-16T17:04:18","modified_gmt":"2023-01-16T16:04:18","slug":"453502-sorpresi-a-sversare-materiale-edile-in-un-terreno-privato-cinque-persone-denunciate","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/453502-sorpresi-a-sversare-materiale-edile-in-un-terreno-privato-cinque-persone-denunciate\/","title":{"rendered":"Sorpresi a sversare materiale edile in un terreno privato. Cinque persone denunciate"},"content":{"rendered":"<p>BOTRICELLO (CZ) &#8211; Sono cinque le persone denunciate dai carabinieri alla Procura di Catanzaro e ritenute a vario titolo presunte responsabili del reato di<strong> \u201cattivit\u00e0 di gestione di rifiuti non autorizzata\u201d. <\/strong>I militari, durante\u00a0 un servizio perlustrativo, hanno sorpreso<strong> il titolare di una ditta di trasporti non autorizzata alla gestione di rifiuti<\/strong> intento a sversare dal proprio autocarro un\u2019ingente quantit\u00e0 di materiale di risulta edile <strong>all\u2019interno di un terreno privato a lui in uso<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/15061\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-453504\" src=\"https:\/\/quicosenza.it\/news\/15061\" alt=\"\" width=\"568\" height=\"355\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019ipotesi \u00e8 che i due soci della predetta ditta di trasporti, si sarebbero accordati con il titolare di un\u2019impresa edile incaricata di eseguire dei<strong> lavori in un cantiere sito nel Comune di Botricello<\/strong>, con il direttore dei lavori e con la proprietaria del terreno sito nel Comune di Andali al fine di smaltire il materiale di risulta ed i rifiuti in maniera illegale, risparmiando sui relativi costi.\u00a0Verificata<strong> l\u2019assenza delle previste autorizzazioni in tema di gestione e smaltimento di rifiuti<\/strong>, i carabinieri hanno quindi sottoposto a sequestro il terreno su cui sono stati scaricati i materiali e l\u2019autocarro utilizzato, e denunciato a piede libero i 5 soggetti, a vario titolo coinvolti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri hanno sequestrato il terreno nel quale erano stati scaricati i materiali insieme all\u2019autocarro utilizzato e denunciato a piede libero le 5 persone<\/p>\n","protected":false},"author":55,"featured_media":168118,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-168117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=168117"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/168118"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=168117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=168117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=168117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}