{"id":168263,"date":"2022-04-27T08:50:28","date_gmt":"2022-04-27T06:50:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/covid-ricciardi-ancora-presto-per-togliere-mascherine-e-green-pass\/"},"modified":"2023-01-16T17:04:29","modified_gmt":"2023-01-16T16:04:29","slug":"453925-covid-ricciardi-ancora-presto-per-togliere-mascherine-e-green-pass","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/453925-covid-ricciardi-ancora-presto-per-togliere-mascherine-e-green-pass\/","title":{"rendered":"Covid, Ricciardi: \u201cancora presto per togliere mascherine e Green Pass\u201d"},"content":{"rendered":"<p>ROMA &#8211; In Italia, dopo oltre due anni di pandemia da Covid-19, \u00e8 ormai prossima la scadenza dell\u2019ultimo decreto con le regole <strong>per contrastare la diffusione del virus Sars-Cov-2<\/strong>. A breve sono attese decisioni in merito, <strong>ma l\u2019idea \u00e8 che il Green Pass possa rimanere utile per dimostrare solo pi\u00f9 l\u2019avvenuta vaccinazione o guarigione,<\/strong> ma non sar\u00e0 pi\u00f9 obbligatorio nei luoghi di lavoro, negli uffici pubblici, nei negozi, nei bar e ristoranti o sui mezzi di trasporto. E l\u2019utilizzo delle mascherine al chiuso dovrebbe restare obbligatorio solamente in situazione specifiche quali la presenza sui mezzi del trasporto pubblico locale e su aerei, navi e treni a lunga percorrenza. <strong>Dopo il 1\u00b0 maggio, le mascherine Ffp2, inoltre, dovrebbero restare obbligatorie ancora in tutti quei luoghi di aggregazione<\/strong> dove si sta a lungo in uno spazio chiuso, con posti ravvicinati, come cinema, teatri e sale da concerto. Oltre che negli ospedali. Una linea prudente su cui concorda anche Walter Ricciardi, consulente del ministro della Salute, Roberto Speranza e docente di Igiene Pubblica presso l\u2019Universit\u00e0 Cattolica, secondo cui \u00e8 ancora troppo presto per eliminare ogni restrizione.<\/p>\n<h4>\u201cSbagliato pensare sia tutto finito\u201d<\/h4>\n<p>Secondo Ricciardi \u201csarebbe sbagliato pensare che sia tutto finito. Sar\u00e0 cos\u00ec se staremo attenti, continuando a proteggerci, a monitorare i focolai epidemici oltre che a vaccinarci\u201d, ha spiegato. <strong>\u201cMentre vedo che la campagna vaccinale si \u00e8 arenata e che c\u2019\u00e8 un calo di attenzione, che fa togliere le mascherine al chiuso e frequentare locali affollati.<\/strong> E l\u2019indicatore finale di questo clima di rilassatezza \u00e8 il numero dei morti, ancora tanti\u201d, ha poi aggiunto. Nel nostro Paese, ha riferito ancora, \u201cabbiamo una popolazione pi\u00f9 anziana,<strong> ma che soprattutto gode di meno salute e di un peggior accesso ai servizi rispetto a Paesi come il Giappone o la Germania, c<\/strong>he hanno un\u2019et\u00e0 media alta come la nostra ma meno decessi. In parecchi casi i pi\u00f9 fragili e i grandi anziani da noi non ce la fanno nemmeno ad arrivare in ospedale\u201d, ha commentato l\u2019esperto. Sottolineando come la quarta dose per i soggetti pi\u00f9 fragili, <strong>\u201cdopo due mesi l\u2019ha fatta appena il 12%, perch\u00e9 si aspetta che sia il paziente a fare il passo e non il medico<\/strong> o la struttura che lo ha in carico a contattarlo e a spiegargli perch\u00e9 \u00e8 opportuno farla\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Vedo che la campagna vaccinale arenata e calo di attenzione che fa togliere le mascherine al chiuso e frequentare locali affollati&#8221;<\/p>\n","protected":false},"author":61,"featured_media":168264,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-168263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=168263"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/168264"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=168263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=168263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=168263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}