{"id":168344,"date":"2022-04-29T15:30:44","date_gmt":"2022-04-29T13:30:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/un-attore-cosentino-nella-serie-di-amazon-che-racconta-la-ndrangheta\/"},"modified":"2023-01-16T17:04:34","modified_gmt":"2023-01-16T16:04:34","slug":"454123-un-attore-cosentino-nella-serie-di-amazon-che-racconta-la-ndrangheta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/454123-un-attore-cosentino-nella-serie-di-amazon-che-racconta-la-ndrangheta\/","title":{"rendered":"Un attore cosentino nella serie di Amazon che racconta la \u2018ndrangheta"},"content":{"rendered":"<p>COSENZA &#8211;<strong> \u00c8 di origine cosentina Carmelo Giordano<\/strong>, uno degli interpreti d<strong>i Bang Bang Baby,<\/strong> la prima fiction interamente italiana di Amazon Original, prodotta in collaborazione con The Apartment e WildSide, entrambe parte del gruppo Fremantle. La serie, i cui primi 5 episodi sono disponibili da oggi su Amazon Prime Video, <strong>\u00e8 una crime story ambientata alla fine degli anni 80 ideata da Andrea Di Stefano,<\/strong> ispirata alla storia vera di Marisa Merico, figlia <strong>di un\u2019ex boss della \u2018ndrangheta<\/strong> che, dopo l\u2019arresto del padre, prende in mano le redini del clan familiare.<\/p>\n<h4>\u201cBang Bang Baby\u201d, una storia di \u2018ndrangheta<\/h4>\n<p>Una fiction dal respiro internazionale, <strong>girata in pieno lockdown seguendo rigidissimi protocolli, e oggi distribuita in 240 paesi<\/strong> dopo la presentazione in anteprima mondiale dei primi due episodi a Roma il 21 aprile. <strong>Bang Bang Baby racconta la storia di Alice Giammatteo<\/strong> \u2013 interpretata da Arianna Becheroni \u2013 un\u2019adolescente che dopo aver scoperto che il padre (Adriano Giannini) non \u00e8 morto come le avevano fatto credere, ma si trova in realt\u00e0 in carcere, a Milano, entra a far parte del mondo criminale per conquistare l\u2019amore paterno. Da ragazzina timida e insicura, si ritrova ad essere il membro pi\u00f9 giovane di un\u2019organizzazione mafiosa, uno storico clan della \u2018ndrangheta calabrese trasferitosi a Milano per fare affari con i politici corrotti, capeggiato dalla temibile nonna Lina (Donna Romano). Per farcela, Alice utilizzer\u00e0 la sua immaginazione, influenzata dalla musica, dalla TV e dalla cultura pop del suo tempo.<\/p>\n<h4>Chi \u00e8 Carmelo Giordano, Nitto Barone in \u201cBang Bang Baby\u201d<\/h4>\n<p>Carmelo Giordano <strong>nasce a Cosenza il 1\u00b0 agosto 1953<\/strong>. Attore di cinema e teatro, incontra il mondo cinematografico quasi casualmente: &#8220;Il cinema si \u00e8 accorto di me quasi per caso nel 2010 \u2013 racconta l\u2019attore \u2013 avevo accompagnato un amico, sprovvisto di auto,<strong> a Castrovillari per un casting.<\/strong> Mentre aspettavo \u00e8 uscita dalla sala casting Laura De Strobel, che si occupava di quel progetto, e mi ha invitato ad entrare. L\u00ec ho conosciuto Alice Rohrwacher e il cinema: sono stato scelto, infatti, per interpretare Ignazio, tuttofare al fianco di Salvatore Cantalupo in Corpo Celeste&#8221;.\u00a0 <strong>Un personaggio ironico, un criminale per certi versi romantico, da tempo innamorato di Lina, \u201cnonna eroina\u201d<\/strong> della quale diventa collaboratore ritrovandosi coinvolto in svariate vicende che lo vedranno protagonista per sette delle dieci puntate della fiction.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carmelo Giordano in \u201cBang Bang Baby\u201d, la storia di un\u2019adolescente che entra a far parte di un clan per conquistare l\u2019amore paterno<\/p>\n","protected":false},"author":61,"featured_media":168345,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[],"class_list":["post-168344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=168344"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/168345"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=168344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=168344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=168344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}