{"id":168501,"date":"2022-05-01T08:46:27","date_gmt":"2022-05-01T06:46:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/primo-maggio-occhiuto-il-mio-pensiero-va-a-chi-un-lavoro-non-ce-lha\/"},"modified":"2023-01-16T17:04:45","modified_gmt":"2023-01-16T16:04:45","slug":"454411-primo-maggio-occhiuto-il-mio-pensiero-va-a-chi-un-lavoro-non-ce-lha","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/454411-primo-maggio-occhiuto-il-mio-pensiero-va-a-chi-un-lavoro-non-ce-lha\/","title":{"rendered":"Primo maggio, Occhiuto &#8220;il mio pensiero va a chi un lavoro non ce l&#8217;ha&#8221;"},"content":{"rendered":"<p>CATANZARO &#8211; \u201dL\u2019Italia \u00e8 una Repubblica democratica, fondata sul lavoro. Queste le prime parole della nostra Costituzione. Oggi, primo maggio, si celebra la festa dei lavoratori, ma il mio pensiero &#8211; da calabrese, Regione agli ultimi posti in Europa per occupazione &#8211; va a chi, soprattutto donne e giovani, un lavoro non lo ha&#8221;. Cos\u00ec il<strong> presidente della Regione Calabria Roberto Occhiuto<\/strong> in una nota in occasione dell&#8217;1 maggio, festa dei lavoratori. Prima di lui anche il vicepresidente del Consiglio Regionale, Giusy Princi, ha lanciato il suo messaggio in una l<a href=\"https:\/\/quicosenza.it\/news\/15107\" target=\"_blank\" rel=\"noopener\">ettera aperta a lavoratori e precari calabresi<\/a>.<\/p>\n<h4>Occhiuto &#8220;superare dualismo lavoratori\/imprenditori&#8221;<\/h4>\n<p>Il governatore vuole rivolgere un pensiero &#8220;anche a chi fa impresa, a chi ogni giorno si barcamena, tra tasse e burocrazia, per alzare la saracinesca della propria attivit\u00e0, e per creare sviluppo e posti di lavoro. <strong>Viviamo un periodo estremamente complicato<\/strong>. Dopo la stagione del Covid adesso il conflitto in Ucraina non lascia presagire tempi semplici con i quali rapportarsi. Occorre, soprattutto in questo scenario, stare uniti.<strong> Serve un patto &#8211; conclude Occhiuto &#8211; tanto a livello nazionale quanto a livello locale<\/strong>, con Regioni e Comuni protagonisti &#8211; tra politica, sindacati e associazioni imprenditoriali, per superare una volta per tutte il dualismo tra lavoratori e imprenditori. Bisogna remare tutti nella stessa direzione per affrontare insieme le sfide del futuro\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cos\u00ec il governatore della Calabria che auspica di &#8220;superare una volta per tutte il dualismo tra lavoratori e imprenditori&#8221;<\/p>\n","protected":false},"author":58,"featured_media":168502,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,1],"tags":[19],"class_list":["post-168501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-senza-categoria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=168501"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/168502"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=168501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=168501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=168501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}