{"id":168779,"date":"2022-05-05T16:46:54","date_gmt":"2022-05-05T14:46:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tragico-incidente-sul-lavoro-muore-operaio-53enne-cadendo-da-una-scala\/"},"modified":"2023-01-16T17:05:03","modified_gmt":"2023-01-16T16:05:03","slug":"454972-tragico-incidente-sul-lavoro-muore-operaio-53enne-cadendo-da-una-scala","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/454972-tragico-incidente-sul-lavoro-muore-operaio-53enne-cadendo-da-una-scala\/","title":{"rendered":"Tragico incidente sul lavoro. Muore operaio 53enne cadendo da una scala"},"content":{"rendered":"<p>CATANZARO &#8211;<strong> Un operaio di 53 anni, Franco Leuzzi, \u00e8 morto oggi in un incidente sul lavoro<\/strong> a Satriano, nel soveratese. L&#8217;uomo, che lavorava come carpentiere in una ditta, \u00e8 caduto da una scala, da un&#8217;altezza di circa tre metri, mentre stava eseguendo dei lavori sul tetto di un&#8217;abitazione. Ogni tentativo di salvargli la vita \u00e8 risultato vano. Sul posto sono intervenuti i carabinieri della Compagnia di Soverato per <strong>accertare la dinamica dell&#8217;incidente<\/strong> ed eventuali responsabilit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un operaio di 53 anni, Franco Leuzzi, \u00e8 morto oggi in un incidente sul lavoro nel soveratese. Ogni tentativo di salvargli la vita \u00e8 risultato vano<\/p>\n","protected":false},"author":58,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-168779","post","type-post","status-publish","format-standard","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=168779"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168779\/revisions"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=168779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=168779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=168779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}