{"id":16882,"date":"2013-01-31T11:39:38","date_gmt":"2013-01-31T10:39:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=16882"},"modified":"2023-01-17T13:14:56","modified_gmt":"2023-01-17T12:14:56","slug":"5885-anas-dal-31-gennaio-senso-unico-alternato-su-106-jonica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/5885-anas-dal-31-gennaio-senso-unico-alternato-su-106-jonica\/","title":{"rendered":"Anas, dal 31 gennaio senso unico alternato su 106 &#8220;Jonica&#8221;"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>CATANZARO<\/strong> &#8211; Dal 31 gennaio a 4 marzo 2013, l&#8217;Anas comunica il senso unico alternato sulla strada statale 106 &#8220;Jonica&#8221;,<\/p>\n<p>  <!--more-->  <\/p>\n<p>precisamente tra il km 173,500 e il km 174,10, a causa di alcuni lavori di ripristino dei giunti di dilatazione del viadotto \u201cLumia\u201d, a Stalett\u00ec, in provincia di Catanzaro.<\/p>\n<p>Il limite da rispettare, in prossimit\u00e0 delle aree di cantiere, \u00e8 di 30 km\/h e il divieto di sorpasso.<\/p>\n<p>E&#8217;raccomandata la massima prudenza. L&#8217;evoluzione della situazione del traffico in tempo reale \u00e8 consultabile sul sito web http:\/\/www.stradeanas.it\/traffico oppure su tutti gli smartphone e i tablet, grazie all`applicazione `VAI Anas Plus`, disponibile gratuitamente in \u201cApp store\u201d e in \u201cPlay store\u201d. Gli utenti hanno poi a disposizione la web tv www.stradeanas.tv e il numero 841-148 \u2018Pronto Anas\u2019 per informazioni sull\u2019intera rete Anas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; CATANZARO &#8211; Dal 31 gennaio a 4 marzo 2013, l&#8217;Anas comunica il senso unico alternato sulla strada statale 106 &#8220;Jonica&#8221;,<\/p>\n","protected":false},"author":22,"featured_media":16883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-16882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=16882"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/16883"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=16882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=16882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=16882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}