{"id":168850,"date":"2022-05-06T20:54:51","date_gmt":"2022-05-06T18:54:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/zilli-goal-fa-esplodere-il-marulla-il-cosenza-centra-i-play-out-contro-il-vicenza\/"},"modified":"2023-01-16T17:05:08","modified_gmt":"2023-01-16T16:05:08","slug":"455123-zilli-goal-fa-esplodere-il-marulla-il-cosenza-centra-i-play-out-contro-il-vicenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/455123-zilli-goal-fa-esplodere-il-marulla-il-cosenza-centra-i-play-out-contro-il-vicenza\/","title":{"rendered":"Zilli goal fa esplodere il Marulla. Il Cosenza centra i play-out contro il Vicenza"},"content":{"rendered":"<p>COSENZA &#8211; \u00c8 servita l<strong>&#8216;invezione del giovanissimo Massimo Zilli<\/strong>\u00a0 al 65&#8242; per cancellare le streghe che aleggiavano sul Marulla e<strong> regalare al Cosenza quella vittoria fondamentale che serviva per centrare i play-out salvezza.<\/strong> Missione compiuta con i rossoblu che si <strong>giocheranno la permanenza in serie B contro il Vicenza <\/strong>che ha espugnato il Moccagatta decretando la retrocessione dell&#8217;Alessandria in Serie C. Una partita intensa e sofferta quella contro il Cittadella, che non ha regalato nulla ai rossoblu che dopo aver sfiorato il vantaggio con Caso nel primo tempo<strong>, <\/strong>nella ripresa alzano i ritmi della gara trovando il goal vittoria al minuto 65&#8242; con il neo entrtato Zilli che fa esplodere i 12mila del Marulla che non hanno smesso per un secondo di incitare la squadra.<\/p>\n<div id=\"attachment_455153\" style=\"width: 563px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/quicosenza.it\/news\/15130\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-455153\" class=\"wp-image-455153\" src=\"https:\/\/quicosenza.it\/news\/15130\" alt=\"\" width=\"553\" height=\"311\" title=\"\"><\/a><p id=\"caption-attachment-455153\" class=\"wp-caption-text\">Foto Francesco Donato<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><strong>La cronaca<\/strong> &#8211; Partono meglio gli ospiti che al 6&#8242; si fanno vedere con <strong>il colpo di testa di Varela<\/strong> che mette i brividi a Matoisevic. Il Cittadella se la gioca colpo su colpo e costringe il Cosenza ad accelerare e soprattutto a non concedere nulla ai veneti che al 10 vanno ancora alla conclusione con Varela. La replica del Cosenza \u00e8 in una\u00a0c<strong>iabattata di Di Pardo<\/strong>. Il Cittadella continua a creare grattacapi alla difesa del Cosenza che non pu\u00f2 concedersi distrazioni. Al 17 <strong>gran sventola di Florenzi dai 30 metri<\/strong> e pallone alto sulla traversa. La gara resta vivace ed equilibrata ma i rossoblu faticano a prendere in mano le redini della gara, trovando pi\u00f9 di una difficolt\u00e0 a calciare verso la porta. Al 25 arriva comunque <strong>la prima grandissima occasione per il Cosenza con il colpo di testa di Caso<\/strong> su un pallone rimesso in area da Di Pardo che chiama Maniero alla grandissima respinta in angolo. Ma \u00e8 un episodio, perch\u00e9 la squadra di Bisoli continua ad avere enormi difficolt\u00e0 nel costruire azioni degne di nota, soprattutto negli ultimi 25 metri dove la difesa del Cittadella ha sempre la meglio.<\/p>\n<p>La <a href=\"https:\/\/quicosenza.it\/news\/15131\">gallery<\/a> di Francesco Donato<\/p>\n\n<p>Le notizie che arrivano da Alessandria non sono confortanti e con il Cosenza costretto a vincere la gara, Bisoli<strong> butta nella mischia anche Laura al posto di Boultam<\/strong> per una squadra ancora pi\u00f9 offensiva. E i rossoblu provano ad aumentare i ritmi della gara, cercando di mettere pressione alla retroguardia del Cittadella. Ma restano le grandi difficolt\u00e0 a concludere in porta. Al 58 ci prova <strong>Larrivey con un colpo di testa<\/strong> che termina largo non di molto, mentre un minuto dopo Laura non riesce a servire lo stesso Larrivey in area. E il momento di massima pressione per i rossoblu che<strong> al 65 trovano finalmente il goal che fa esplodere il Marulla<\/strong> con il giovanissimo Massimo Zilli che <strong>si avventa un cross dalla destra di Liotti e di testa manda il pallone prima a baciare il palo e poi a gonfiare la rete<\/strong>. Un goal liberazione per il Marulla e per il Cosenza che con il vantaggio in tyasca, cerca di addormentare la gara senza pi\u00f9 la frenesia di dover trovare il goal. Operazione che riesce alla perfezione fino al triplice fischio finale che decreta il successo dei rossoblu che ora si giocheranno la Serie B nella doppia sfida contro il Vicenza e con il piccolissimo vantaggio di giocare il ritorno al Marulla.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p><strong>COSENZA CALCIO (3-5-2):<\/strong> Matosevic; Vaisanen, Rigione, Venturi (12\u2032 st Zilli); Di Pardo, Boultam (1\u2032 st Laura), Gerbo (12\u2032 st Carraro), Florenzi, Liotti; Larrivey (25\u2032 st Kongolo), Caso (40\u2032 st Bittante)<br \/>\n<strong>A disposizione<\/strong>: Sarri, Vallocchia, Voca, Arioli, Hristov, Ndoj, Situm<br \/>\n<strong>Allenatore:<\/strong>\u00a0Pierpaolo Bisoli<\/p>\n<p><strong>CITTADELLA CALCIO (4-4-1)<\/strong>: Maniero, Visentin, Frare, Donnarumma, Laribi, Tavernelli (36\u2032 st Beretta), Branca, Icardi (15\u2032 st Mastrantonio), Lores Varela (21\u2032 st Thioune), Danzi (15\u2032 st Mazzocco), Cassandro (36\u2032 st Ciriello)\u00a0<strong>A disposizione<\/strong>: Manfrin, Kastrati, Perticone, Del Fabro, Pavan, Antonucci<br \/>\n<strong>Allenatore:<\/strong> Edoardo Gorini<\/p>\n<p><strong>Arbitro:<\/strong> Signor Davide Ghersini di Genova<br \/>\n<strong>Assistenti:<\/strong> Signori Dario Cecconi di Empoli e Alessandro Cipressa di Lecce<br \/>\n<strong>IV Uomo:<\/strong> Signor Marco Acanfora\u00a0di Castellammare di Stabia<br \/>\n<strong>SALA VAR:<\/strong> Signori Marco Serra di Torino e Michele Grossi di Frosinone<\/p>\n<p><strong>Ammoniti: <\/strong>Danzi (V) , Visentin (V), Zilli (C)<br \/>\n<strong>Espulsi:\u00a0<\/strong><\/p>\n<p><strong>Angoli: <\/strong>4-1<br \/>\n<strong>Recupero:<\/strong> 0&#8242; p.t &#8211; 4&#8242; s.t.<\/p>\n<p><strong>Note:<\/strong> Serata gradevole a Cosenza con una temperatura di circa 17 gradi. Terreno del Marulla in perfette condizioni. Presenti poco meno di 13.000 spettatori.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un colpo di testa del giovane Zilli a met\u00e0 secondo tempo regala il successo al Cosenza che si giocher\u00e0 la permanenza in Serie B contro il Vicenza. Alessandria in serie C<\/p>\n","protected":false},"author":24,"featured_media":168851,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[19],"class_list":["post-168850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=168850"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/168851"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=168850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=168850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=168850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}