{"id":168900,"date":"2022-05-07T16:21:42","date_gmt":"2022-05-07T14:21:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/aemilia-oltre-70-condanne-confermate-in-cassazione-emilia-romagna-distretto-di-mafia\/"},"modified":"2023-01-16T17:05:11","modified_gmt":"2023-01-16T16:05:11","slug":"455231-aemilia-oltre-70-condanne-confermate-in-cassazione-emilia-romagna-distretto-di-mafia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/455231-aemilia-oltre-70-condanne-confermate-in-cassazione-emilia-romagna-distretto-di-mafia\/","title":{"rendered":"&#8220;Aemilia&#8221;, oltre 70 condanne anche in Cassazione: \u00abEmilia Romagna distretto di mafia\u00bb"},"content":{"rendered":"<p>BOLOGNA &#8211; Trentasei ricorsi rigettati, 39 dichiarati inammissibili, mentre per 13 posizioni sono stati disposti annullamenti con lievi ricalcoli di pene o rinvii limitatamente a pochi capi d&#8217;accusa. La <strong>Corte di Cassazione<\/strong> ha ampiamente confermato le condanne decise della Corte di appello di Bologna nel maxi-processo di &#8216;Ndrangheta &#8216;<strong>Aemilia<\/strong>&#8216; e cos\u00ec pure il quadro accusatorio della storica grande operazione contro le infiltrazioni e il radicamento della <strong>criminalit\u00e0 organizzata calabrese in Emilia-Romagna, <\/strong>scattata nel 2015<strong> con 117 arresti.<\/strong><\/p>\n<p>Si tratta del <strong>secondo riconoscimento della Cassazione<\/strong> all&#8217;impostazione accusatoria di &#8216;<strong>Aemilia<\/strong>&#8216;, dopo quello arrivato nel 2018 con <strong>40 condanne definitive agli imputati che avevano scelto l&#8217;abbreviato<\/strong>, tra cui diversi capi e organizzatori dell&#8217;associazione &#8216;ndranghetistica emiliana legata alla <strong>Cosca Grande Aracri di Cutro<\/strong>.<\/p>\n<p>Per chi ha percorso la via del dibattimento la Corte di Appello di Bologna aveva inflitto a dicembre 2020 oltre 700 anni di carcere complessivi, a <strong>91 persone.<\/strong> Erano 87 quelli ricorsi al terzo grado di giudizio. Tra questi Michele Bolognino, uno di coloro ai quali \u00e8 stata rideterminata la pena, a 20 anni e 10 mesi, per la prescrizione di un&#8217;accusa.<\/p>\n<p>Confermata la condanna a <strong>Giuseppe Iaquinta<\/strong>, imprenditore e <strong>padre dell&#8217;ex calciatore della Juventus<\/strong> e della Nazionale campione del mondo: 13 anni. Il figlio, condannato a due anni con la condizionale per irregolarit\u00e0 nella custodia di armi, non aveva fatto ricorso. Tra gli imputati anche l&#8217;imprenditore modenese <strong>Augusto Bianchini<\/strong> (9 anni), <strong>Gaetano Blasco<\/strong> (21 anni e 11 mesi), <strong>Alfredo e Francesco Amato<\/strong>, rispettivamente 17 anni e 16 anni e 9 mesi; <strong>Giuseppe e Palmo Vertinelli<\/strong>, 16 anni e 4 mesi e 17 anni e 4 mesi.<\/p>\n<h4>Il procuratore di Bologna \u00absentenza dimostra che l&#8217;Emilia Romagna \u00e8 distretto di mafia\u00bb<\/h4>\n<p>&#8220;La sentenza &#8216;Aemilia&#8217; con il suo passaggio in giudicato, la nona in ordine temporale per associazione di stampo mafioso in Emilia-Romagna, conferma che l&#8217;Emilia-Romagna \u00e8 un distretto di mafia&#8221;. <strong>Lucia Musti<\/strong>, procuratrice generale reggente a Bologna e che peraltro rappresent\u00f2 la pubblica accusa nel processo di appello, commenta cos\u00ec all&#8217;ANSA l&#8217;esito della Cassazione, riprendendo le sue stesse parole per la relazione in apertura dell&#8217;anno giudiziario.<\/p>\n<p>La sentenza, prosegue Musti, &#8220;\u00e8 il frutto del lavoro della Dda di Bologna, della Procura generale di Bologna e della Procura generale presso la Corte di Cassazione. Ringrazio tutte la polizia giudiziaria, in particolar modo i carabinieri dei comandi provinciali di Modena, Parma e Piacenza, per l&#8217;altissima professionalit\u00e0 e il massimo impegno profuso nelle indagini&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confermata anche la condanna a Giuseppe Iaquinta, imprenditore e padre dell&#8217;ex calciatore della Juventus e della Nazionale campione del mondo<\/p>\n","protected":false},"author":42,"featured_media":168901,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-168900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=168900"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/168901"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=168900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=168900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=168900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}