{"id":168910,"date":"2022-05-08T10:00:15","date_gmt":"2022-05-08T08:00:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/bonus-per-i-trasporti-pubblici-da-60-euro-a-chi-spetta-e-come-usufruirne\/"},"modified":"2023-01-16T17:05:12","modified_gmt":"2023-01-16T16:05:12","slug":"455271-bonus-per-i-trasporti-pubblici-da-60-euro-a-chi-spetta-e-come-usufruirne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/455271-bonus-per-i-trasporti-pubblici-da-60-euro-a-chi-spetta-e-come-usufruirne\/","title":{"rendered":"Bonus per i trasporti pubblici da 60 euro: a chi spetta e come usufruirne"},"content":{"rendered":"<p>COSENZA &#8211; Pioggia di incentivi dal Governo: arriva anche il <strong>bonus 60 euro<\/strong>\u00a0per i trasporti pubblici riconosciuto a\u00a0<strong>studenti e lavoratori<\/strong>\u00a0che hanno un reddito\u00a0<strong>inferiore a 35mila euro<\/strong>, un contributo economico per mitigare gli effetti negativi dell\u2019aumento dei prezzi sull\u2019economia familiare.<\/p>\n<p>La misura \u00e8 stata introdotta nel Decreto Aiuti 2022, in occasione del secondo passaggio in Consiglio dei Ministri del 5 maggio 2022, e il Governo ha istituito\u00a0<strong>un fondo ad hoc<\/strong>\u00a0per finanziarlo.<\/p>\n<h4>Bonus trasporti, che cos&#8217;\u00e8<\/h4>\n<p>Il Governo ha stanziato un fondo di 100 milioni di euro per il 2022 da destinare alla creazione di\u00a0<strong>un buono da utilizzare per l\u2019acquisto di abbonamenti<\/strong>\u00a0per i servizi di trasporto pubblico locale, regionale e interregionale o per il trasporto ferroviario nazionale. Il bonus trasporti copre il 100% della spesa sostenuta, entro un limite massimo di<strong>\u00a060 euro<\/strong>.<\/p>\n<h4>Chi lo pu\u00f2 richiedere<\/h4>\n<p>Il bonus trasporti pu\u00f2 esser richiesto solo da chi ha posseduto nel 2021 un reddito personale lordo annuo di\u00a0<strong>massimo 35.000 euro<\/strong>. Quindi certificazioni uniche alla mano, occorre verificare\u00a0<strong>l\u2019importo del reddito imponibile che verr\u00e0 indicato anche nel 730<\/strong>\u00a0o nel modello Redditi di prossima presentazione. I redditi interessati sono quindi tutti quelli dichiarati e imponibili ai fini fiscali,\u00a0<strong>non solo quelli da lavoro o da pensione<\/strong>, come ad esempio gli affitti per i quali si paga la cedolare secca.<\/p>\n<h4>Come fare domanda<\/h4>\n<p>Entro i prossimi due mesi verr\u00e0 emanato un decreto che stabilir\u00e0\u00a0<strong>le modalit\u00e0 per presentare la domanda<\/strong>. Al momento sappiamo che verr\u00e0 predisposta una\u00a0<strong>piattaforma informatica<\/strong> in cui inserire la richiesta, che seguir\u00e0 l\u2019ordine di arrivo.<\/p>\n<h4>Come usarlo<\/h4>\n<p>Sul bonus viene indicato\u00a0<strong>il nominativo del beneficiario<\/strong>\u00a0ed \u00e8 utilizzabile per l\u2019acquisto di\u00a0<strong>un solo abbonamento<\/strong>\u00a0e non \u00e8 cedibile. Quindi se in famiglia ci sono pi\u00f9 persone che utilizzano i mezzi pubblici,\u00a0<strong>ogni componente deve fare la propria richiesta<\/strong>, ovviamente sempre se rispetta i limiti di reddito necessari per averne diritto.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel decreto aiuti \u00e8 stato introdotto un contributo per acquistare l&#8217;abbonamento a mezzi pubblici locali, regionali, interregionali e treni<\/p>\n","protected":false},"author":58,"featured_media":168911,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-168910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=168910"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/168911"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=168910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=168910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=168910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}