{"id":168944,"date":"2022-05-09T08:50:15","date_gmt":"2022-05-09T06:50:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/da-scalea-nel-napoletano-per-rapinare-una-gioielleria-quattro-arresti\/"},"modified":"2023-01-16T17:05:14","modified_gmt":"2023-01-16T16:05:14","slug":"455350-da-scalea-nel-napoletano-per-rapinare-una-gioielleria-quattro-arresti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/455350-da-scalea-nel-napoletano-per-rapinare-una-gioielleria-quattro-arresti\/","title":{"rendered":"Da Scalea nel napoletano per rapinare una gioielleria, quattro arresti"},"content":{"rendered":"<p>SAN GIUSEPPE VESUVIANO (NA) &#8211; I fatti risalgono a venerd\u00ec mattina quando polizia e carabinieri sono intervenuti in via San Leonardo a San Giuseppe Vesuviano dove era stata segnalata una rapina in una gioielleria. Le forze dell\u2019ordine giunte sul posto, sono entrate immediatamente nell\u2019esercizio commerciale riuscendo a bloccare quattro persone, che avevano gi\u00e0 trafugato e messo in due sacchi gioielli, orologi, monili in oro e denaro in contanti. Fuori dal negozio di preziosi \u00e8 stato trovato un motoveicolo utilizzato da uno dei quattro a cui era stata apposta la targa di un altro mezzo.<\/p>\n<p>Secondo gli accertamenti, poco prima del colpo, una donna fingendosi interessata all\u2019acquisto di un gioiello, aveva distratto una dipendente mentre i complici, entrati nel negozio, dopo aver rubato alcuni preziosi dagli espositori hanno <strong>intimato alla commessa di aprire la cassa.<\/strong> Gli arrestati sono <strong>un 44enne di Scafati, un 47enne ed un 54enne entrambi di Scalea, tutti con precedenti di polizia, e una donna di 55 anni, anche lei di Scalea,<\/strong> arrestati per tentata rapina. Due di loro inoltre, il 47enne e il 54enne, erano sottoposti all\u2019obbligo di dimora nel comune di Scalea, sono stati altres\u00ec denunciati per la violazione degli obblighi inerenti la misura cui sono sottoposti. La merce rubata invece, \u00e8 stata restituita al proprietario dell\u2019attivit\u00e0 commerciale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;intervento delle forze dell\u2019ordine ha portato all&#8217;arresto di quattro persone, tre delle quali di Scalea. La merce \u00e8 stata riconsegnata al proprietario<\/p>\n","protected":false},"author":42,"featured_media":168945,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[19],"class_list":["post-168944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=168944"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/168944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/168945"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=168944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=168944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=168944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}