{"id":16930,"date":"2013-01-31T16:20:18","date_gmt":"2013-01-31T15:20:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=16930"},"modified":"2023-01-17T13:14:58","modified_gmt":"2023-01-17T12:14:58","slug":"5910-spaccio-in-campus-universitario","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/5910-spaccio-in-campus-universitario\/","title":{"rendered":"Spaccio in Campus universitario"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CATANZARO<\/strong> &#8211; Si e&#8217; chiuso con un patteggiamento il processo a carico di Francesco Leone, catanzarese di 31 anni, arrestato con l&#8217;accusa di aver detenuto<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">e spacciato droga nei pressi del campus di Catanzaro, presumibilmente agli studenti universitari. Il giudice monocratico del capoluogo ha inflitto a Leone cinque mesi di reclusione, con concessione della sospensione condizionale della pena e non menzione nel casellario giudiziale, come richiesto dall&#8217;avvocato Anna Marziano, con il consenso del pubblico ministero d&#8217;udienza.<\/p>\n<p style=\"text-align: justify;\">A Leone, arrestato assieme ad un amico in localita&#8217; Baia dei Canonici, nel territorio comunale di Borgia, dove i due giovani vivono, i carabinieri hanno trovato 14,732 grammi di marijuana e un bilancino di precisione mentre nell&#8217;appartamento di A.D.L., un secondo indagato per il quale non e&#8217; stato pero&#8217; convalidato l&#8217;arresto, c&#8217;era una serra botanica con 16 bicchieri di plastica contenenti terriccio e, in 13 di essi, piantine marijuana di altezza variabile dai 3 ai 10 centimetri oltre a una plafoniera con luci ad alto potenziale, una ventola e un temporizzatore collegati alla rete elettrica.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Si e&#8217; chiuso con un patteggiamento il processo a carico di Francesco Leone, catanzarese di 31 anni, arrestato con l&#8217;accusa di aver detenuto<\/p>\n","protected":false},"author":22,"featured_media":16931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-16930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=16930"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/16931"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=16930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=16930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=16930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}