{"id":16936,"date":"2013-02-01T09:47:47","date_gmt":"2013-02-01T08:47:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=16936"},"modified":"2023-01-17T13:14:59","modified_gmt":"2023-01-17T12:14:59","slug":"5913-minaccia-il-suicidio-lo-salva-un-vigile-del-fuoco","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/5913-minaccia-il-suicidio-lo-salva-un-vigile-del-fuoco\/","title":{"rendered":"Minaccia il suicidio: lo salva un vigile del fuoco"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA<\/strong> &#8211; Strada paralizzata. Il traffico veicolare lungo le arterie del cuore antico della citt\u00e0 \u00e8 rimasto, per quasi, un&#8217;ora paralizzato. non per colpa di un incidente, non<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">per causa di un ingorgo, ma per la minaccia di suicidio di un noto professionista ultranovantenne, un vecchio principe del foro cittadino, che ha cercato di farla finita, tentando di farsi travolgere dalle auto in transito. Se la tragedia non s&#8217;\u00e8 consumata, lo si deve alla prontezza di riflessi e all&#8217;intervento tempestivo di un vigile del fuoco, Ugo Rocchetti. Il pompiere, fuori dal turno di servizio, si trovava per ragioni personali, sulla scena del tentato suicidio. E&#8217; stato lui a &#8220;spostare&#8221; di peso il vecchio principe del foro e ad allertare i soccorsi, chiamando sia la polizia provinciale, che la sala operativa del 118, nonch\u00e8 la centrale del 112. In attesa del&#8217;arrivo dei soccorsi, il vigile del fuoco ha &#8220;marcato&#8221; ad uomo l&#8217;aspirante suicida, evitando che riuscisse a mettere in atto il suo gesto estremo. Solo l&#8217;intervento delle forze dell&#8217;ordine ha riportato la calma e ridato aria alla circolazione stradale. Il pensionato per lunghi momenti s&#8217;\u00e8 coricato per strada, bloccando il traffico. I sanitari del 118, al loro arrivo sul posto dell&#8217;sos, si sono resi conto delle condizioni del pensionato, apparso confuso, disorientato. Ora \u00e8 in ospedale, per controlli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Strada paralizzata. Il traffico veicolare lungo le arterie del cuore antico della citt\u00e0 \u00e8 rimasto, per quasi, un&#8217;ora paralizzato. non per colpa di un incidente, non<\/p>\n","protected":false},"author":22,"featured_media":16937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-16936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=16936"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/16936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/16937"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=16936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=16936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=16936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}