{"id":169634,"date":"2022-05-20T16:17:54","date_gmt":"2022-05-20T14:17:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/grave-scontro-tra-auto-sulla-statale-682-un-morto-e-tre-feriti\/"},"modified":"2023-01-16T17:06:01","modified_gmt":"2023-01-16T16:06:01","slug":"456893-grave-scontro-tra-auto-sulla-statale-682-un-morto-e-tre-feriti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/456893-grave-scontro-tra-auto-sulla-statale-682-un-morto-e-tre-feriti\/","title":{"rendered":"Grave scontro tra auto sulla statale 682: un morto e tre feriti"},"content":{"rendered":"<p class=\"v1x_MsoNormal\">REGGIO CALABRIA &#8211; Una squadra dei Vigili del fuoco del comando di Reggio Calabria distaccamento di Polistena \u00e8 impegnata sulla <strong>Strada Statale 682 SGC \u201cJonio-Tirreno\u201d<\/strong> in prossimit\u00e0 del comune di Melicucco, in provincia di Reggio Calabria, per incidente stradale. Per cause ancora in corso di accertamento, il sinistro ha coinvolto due autovetture. <strong>Il bilancio dell&#8217;incidente \u00e8 di una persona deceduta e tre feriti<\/strong>. Sul posto i vigili hanno estratto uno dei feriti dalle lamiere dell&#8217;auto. Lo stesso, in gravi condizioni, \u00e8 stato affidato alle cure dei sanitari del Suem118 che, con l&#8217;ausilio di elisoccorso, hanno provveduto al trasporto immediato presso struttura ospedaliera.<\/p>\n<p class=\"v1x_MsoNormal\">Sul posto <strong>polizia stradale<\/strong> per gli adempimenti di competenza e <strong>personale Anas<\/strong> per il ripristino delle normali condizioni di sicurezza della sede stradale. Attualmente la SS 682 chiusa al transito in ambedue i sensi di marcia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La strada &#8220;Jonio-Tirreno&#8221; \u00e8 temporaneamente chiusa in entrambe le direzioni a Rosarno in provincia di Reggio Calabria<\/p>\n","protected":false},"author":58,"featured_media":169635,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-169634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/169634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=169634"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/169634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/169635"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=169634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=169634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=169634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}