{"id":169703,"date":"2022-05-22T16:31:56","date_gmt":"2022-05-22T14:31:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/paura-sulla-statale-280-auto-si-ribalta-ferito-estratto-dalle-lamiere\/"},"modified":"2023-01-16T17:06:05","modified_gmt":"2023-01-16T16:06:05","slug":"457064-paura-sulla-statale-280-auto-si-ribalta-ferito-estratto-dalle-lamiere","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/457064-paura-sulla-statale-280-auto-si-ribalta-ferito-estratto-dalle-lamiere\/","title":{"rendered":"Paura sulla statale 280, auto si ribalta: ferito estratto dalle lamiere"},"content":{"rendered":"<p>CATANZARO &#8211; Squadra dei Vigili del fuoco del comando di Catanzaro sede centrale \u00e8 intervenuta alle ore 15.00 circa sulla<strong> Strada Statale 280 al km 14,100 direzione Lamezia Terme<\/strong> per incidente stradale. La vettura coinvolta una Fiat Punto che per cause in corso di accertamento<strong> ha perso il controllo ribaltandosi sulla strada<\/strong>. A bordo il solo conducente che \u00e8 stato affidato al personale sanitario del <strong>Suem118<\/strong> per le cure del caso e successivo trasporto in ospedale. L&#8217;intervento dei vigili del fuoco \u00e8 valso altres\u00ec alla messa in sicurezza del sito e della vettura. Sul posto polizia stradale per gli adempimenti di competenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A bordo il solo conducente che \u00e8 stato affidato al personale sanitario del Suem118 e trasferito in ospedale<\/p>\n","protected":false},"author":58,"featured_media":169704,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,1],"tags":[19],"class_list":["post-169703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-senza-categoria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/169703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=169703"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/169703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/169704"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=169703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=169703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=169703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}