{"id":169797,"date":"2022-05-24T10:31:38","date_gmt":"2022-05-24T08:31:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/benessere-animali-in-arrivo-pagamenti-per-5-milioni-e-mezzo\/"},"modified":"2023-01-16T17:06:12","modified_gmt":"2023-01-16T16:06:12","slug":"457255-benessere-animali-in-arrivo-pagamenti-per-5-milioni-e-mezzo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/457255-benessere-animali-in-arrivo-pagamenti-per-5-milioni-e-mezzo\/","title":{"rendered":"Benessere animali: in arrivo pagamenti per 5 milioni e mezzo"},"content":{"rendered":"<p>CATANZARO &#8211;\u00a0 \u00c8 disponibile sul portale istituzionale www.calabriapsr.it <strong>la graduatoria definitiva della misura 14 del Psr Calabria \u201cBenessere degli animali\u201d<\/strong>, valida per l\u2019annualit\u00e0 2021, con la quale, a seguito dell\u2019istruttoria delle istanze di riesame pervenute, sono risultati essere ammissibili 970 interventi, per una stima complessiva di premio pari a 5.498.674,58 euro. <strong>Un sostegno concreto al comparto della zootecnica regionale.<\/strong><\/p>\n<p>Con riferimento all\u2019annualit\u00e0 2022, invece, verr\u00e0 utilizzata la restante parte <strong>della dotazione complessiva della misura 14, pari a 8 milioni, eventualmente integrata da economie<\/strong>. \u00abA causa delle gravi e tangibili difficolt\u00e0 delle aziende zootecniche regionali causate dalla pandemia e dall\u2019aumento dei prezzi delle materie prime indispensabili per l\u2019alimentazione animale \u2013 commenta l\u2019Assessore regionale all\u2019Agricoltura, <strong>Gianluca Gallo &#8211;<\/strong> abbiamo deciso di incrementare la dotazione annuale del bando, finanziando tutte le domande ammissibili, cos\u00ec da favorire il lavoro quotidiano degli allevatori calabresi <strong>attraverso una misura fondamentale, finalizzata a promuovere interventi per migliorare le condizioni<\/strong> di benessere animale e determinare un miglioramento della qualit\u00e0 delle produzioni zootecniche\u00bb.<\/p>\n<p>L\u2019erogazione dei premi in favore dei beneficiari avr\u00e0 luogo a partire dalle prossime ore. L\u2019amministrazione regionale <strong>si riserva la facolt\u00e0 di subordinare i pagamenti ad eventuali riduzioni lineari, qualora la disponibilit\u00e0 finanziaria<\/strong> dovesse rivelarsi insufficiente per la copertura di tutte le domande ammissibili.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalla Regione Calabria sostegno al comparto della zootecnia. Pubblicata la graduatoria definitiva della misura 14 del Psr<\/p>\n","protected":false},"author":61,"featured_media":169798,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,1],"tags":[19],"class_list":["post-169797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-senza-categoria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/169797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=169797"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/169797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/169798"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=169797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=169797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=169797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}