{"id":169839,"date":"2022-05-25T04:57:40","date_gmt":"2022-05-25T02:57:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scossa-di-terremoto-nella-notte-epicentro-a-montalto\/"},"modified":"2023-01-16T17:06:15","modified_gmt":"2023-01-16T16:06:15","slug":"457320-scossa-di-terremoto-nella-notte-epicentro-a-montalto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/457320-scossa-di-terremoto-nella-notte-epicentro-a-montalto\/","title":{"rendered":"Scossa di terremoto nella notte, epicentro a Montalto"},"content":{"rendered":"<p>MONTALTO UFFUGO (CS) &#8211; Una scossa di terremoto di magnitudo <strong>2.4 \u00e8 stata registrata alle 2.38<\/strong> con epicentro a 3 km da Montalto Uffugo ad una profondit\u00e0 di<strong> soli 7 chilometri<\/strong>. L\u2019evento sismico \u00e8 stato avvertito anche in altri comuni della Media Valle del Crati tra cui Luzzi, Rose, San Vincenzo la Costa, Lattarico e altri centri limitrofi. Non si segnalano comunque danni a persone o cose.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;evento sismico \u00e8 stato registrato dai sismografi dell&#8217;Istituto nazionale di Geofisica e Vulcanologia nel cuore della notte<\/p>\n","protected":false},"author":42,"featured_media":169840,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,566],"tags":[19],"class_list":["post-169839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-montalto","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/169839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=169839"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/169839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/169840"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=169839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=169839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=169839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}