{"id":169905,"date":"2022-05-26T05:22:52","date_gmt":"2022-05-26T03:22:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/monsignor-francesco-savino-eletto-vicepresidente-per-larea-sud-della-cei\/"},"modified":"2023-01-16T17:06:20","modified_gmt":"2023-01-16T16:06:20","slug":"457500-monsignor-francesco-savino-eletto-vicepresidente-per-larea-sud-della-cei","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/457500-monsignor-francesco-savino-eletto-vicepresidente-per-larea-sud-della-cei\/","title":{"rendered":"Monsignor Francesco Savino eletto vicepresidente per l&#8217;area sud della CEI"},"content":{"rendered":"<p>CASSANO ALLO IONIO (CS) &#8211; L&#8217;assemblea generale della Conferenza Episcopale Italiana ha eletto questa sera il vice presidente per l&#8217;Area Sud. Si tratta di mons. <strong>Francesco Savino<\/strong>, vescovo di Cassano allo Ionio. Nato a Bitonto (Bari) il 13 novembre 1954, Savino \u00e8 entrato nel Seminario Regionale di Molfetta dopo aver conseguito la maturit\u00e0 classica al Liceo Classico &#8220;C. Sylos&#8221; di Bitonto, nel 1973.<\/p>\n<p><strong>Ordinato sacerdote il 24 agosto 1978<\/strong>, \u00e8 stato nominato vice-parroco della parrocchia San Silvestro-Crocifisso. Il 20 gennaio 1985 \u00e8 stato nominato parroco della parrocchia Cristo Re Universale di Bitonto e quattro anni dopo rettore della parrocchia Santuario Santi Medici. Da sempre attento alle fragilit\u00e0 e ai problemi dovuti all&#8217;illegalit\u00e0 diffusa e impegnato per l&#8217;accoglienza, il <strong>28 febbraio 2015 \u00e8 stato eletto da papa Francesco vescovo della Diocesi di Cassano allo Ionio.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Vescovi italiani ieri hanno espresso con il voto l\u2019apprezzamento per l\u2019impegno pastorale del vescovo di Cassano che andr\u00e0 a ricoprire per un quinquennio il servizio all\u2019interno del Consiglio Permanente della Cei<\/p>\n","protected":false},"author":65,"featured_media":169906,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[19,135],"class_list":["post-169905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia","tag-copertina","tag-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/169905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=169905"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/169905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/169906"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=169905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=169905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=169905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}