{"id":169956,"date":"2022-05-29T08:00:57","date_gmt":"2022-05-29T06:00:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/terapia-del-dolore-e-cure-palliative-al-sud-lassistenza-e-una-odissea\/"},"modified":"2023-01-16T17:06:23","modified_gmt":"2023-01-16T16:06:23","slug":"457615-terapia-del-dolore-e-cure-palliative-al-sud-lassistenza-e-una-odissea","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/457615-terapia-del-dolore-e-cure-palliative-al-sud-lassistenza-e-una-odissea\/","title":{"rendered":"Terapia del dolore e cure palliative, al Sud l&#8217;assistenza \u00e8 &#8220;una Odissea&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; Sono oltre mezzo milione gli italiani che hanno bisogno di cure palliative e milioni sono in una condizione che richiederebbe<strong> terapie del dolore<\/strong> ma, a ventidue anni dall&#8217;approvazione della legge 38 &#8216;Disposizioni per garantire l&#8217;accesso alle cure palliative e alla terapia del dolore&#8217;, restano ancora forti le differenze tra le Regioni e per molti pazienti la ricerca di centri e percorsi specifici di assistenza diventa &#8220;una Odissea&#8221;. Lo ha affermato il presidente della Fondazione nazionale Gigi Ghirotti onlus, Vincenzo Morgante, alla presentazione al ministero della Salute della XXI<strong> Giornata Nazionale del Sollievo<\/strong>, organizzata dalla Fondazione, che si celebra il 29 maggio. &#8220;Alcuni passi decisivi in avanti sono stati compiuti per la diffusione delle cure palliative, ma siamo ancora indietro nell&#8217;implementazione delle reti della terapia del dolore sul territorio. Per questo &#8211; ha affermato Morgante &#8211; <strong>chiediamo la creazione di unit\u00e0 cliniche ambulatoriali della terapia del dolore<\/strong>, l&#8217;avvio di campagne di sensibilizzazione sul dolore cronico e corsi di formazione e aggiornamento sul dolore cronico rivolti ai medici&#8221;.<\/p>\n<p>Una delle maggiori criticit\u00e0 \u00e8 per\u00f2 proprio rappresentata dalle differenze territoriali: &#8220;Al Centro-sud questi servizi mancano e ci\u00f2 significa che per tanti malati, soprattutto oncologici, la ricerca di terapie del dolore e assistenza ad hoc si trasforma in una &#8216;Odissea&#8217; e alla fine &#8211; ha sottolineato &#8211; <strong>molti sono costretti a rivolgersi a strutture private<\/strong>&#8220;. La situazione per\u00f2 sta cambiando anche perch\u00e8, ha affermato il sottosegretario alla Salute Pierpaolo Sileri, &#8220;oggi c&#8217;\u00e8 una maggiore disponibilit\u00e0 economica e pi\u00f9 fondi, grazie al Pnrr e all&#8217;innalzamento del Fondo sanitario nazionale&#8221;.<\/p>\n<h4>Sileri &#8220;recuperemo quello che non \u00e8 stato fatto prima&#8221;<\/h4>\n<p>La legge 38, ha sottolineato Sileri, &#8220;\u00e8 molto innovativa ma negli anni scorsi ci sono state difficolt\u00e0 applicative. Ora c&#8217;\u00e8 un giro di boa e la strada \u00e8 in discesa rispetto a prima e anche l&#8217;interlocuzione con le Regioni \u00e8 maggiore&#8221;. Ci\u00f2 anche perch\u00e8, ha spiegato, &#8220;in questi tre anni di pandemia \u00e8 cambiato l&#8217;atteggiamento verso la sanit\u00e0 e si \u00e8 capito che il processo di cura \u00e8 un percorso e non \u00e8 semplicemente far quadrare i conti e la pandemia ci ha insegnato a pensare diversamente. Oggi inoltre c&#8217;\u00e8 <strong>maggiore disponibilit\u00e0 economica<\/strong> grazie al <strong>Pnrr<\/strong> ma soprattutto grazie all&#8217;innalzamento del <strong>Fondo sanitario nazionale che \u00e8 arrivato a 124 mld<\/strong>. Dunque, recupereremo quello che non \u00e8 stato fato prima&#8221;. Il gap tra le Regioni \u00e8 stato evidenziato anche dal presidente della Societ\u00e0 italiana di anestesia, analgesia, rianimazione e terapia intensiva (Siaarti) Antonino Giarratano: &#8220;Sono 545mila gli italiani che hanno bisogno di cure palliative. La rete della terapia dovrebbe diventare mandatoria per le Regioni e non essere lasciata alle decisioni dei singoli territori&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo ha affermato il presidente della Fondazione nazionale Gigi Ghirotti onlus alla presentazione al ministero della Salute<\/p>\n","protected":false},"author":58,"featured_media":169957,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-169956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/169956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=169956"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/169956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/169957"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=169956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=169956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=169956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}