{"id":170198,"date":"2022-05-31T07:19:19","date_gmt":"2022-05-31T05:19:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/corigliano-rossano-trova-la-chiesa-chiusa-e-da-fuoco-allauto-del-sacerdote\/"},"modified":"2023-01-16T17:06:39","modified_gmt":"2023-01-16T16:06:39","slug":"458258-corigliano-rossano-trova-la-chiesa-chiusa-e-da-fuoco-allauto-del-sacerdote","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/458258-corigliano-rossano-trova-la-chiesa-chiusa-e-da-fuoco-allauto-del-sacerdote\/","title":{"rendered":"Corigliano Rossano, trova la chiesa chiusa e d\u00e0 fuoco all&#8217;auto del sacerdote"},"content":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; Trova chiusa la chiesa di Schiavonea, <strong>bussa con insistenza ma non apre nessuno perch\u00e9 \u00e8 notta fonda.<\/strong> Cos\u00ec un uomo, di origine ucraina, va in escandescenza e tenta di darsi fuoco e d\u00e0 fuoco all\u2019auto del parroco.<\/p>\n<p>L\u2019episodio si \u00e8 verificato questa notte nell\u2019area urbana di Corigliano. Sul posto i carabinieri del reparto operativo di Corigliano Rossano e un mezzo dei vigili del fuoco.<strong> L\u2019uomo \u00e8 stato posto in stato di fermo e denunciato<\/strong>. Sul caso prosegue il lavoro investigativo dei carabinieri diretti dal tenente colonnello <strong>Raffaele Giovinazzo.<\/strong> Non sono ancora chiare le dinamiche ed i motivi che avrebbero spinto l&#8217;uomo ad appiccare il fuoco all\u2019auto del sacerdote.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;uomo, di origine ucraina, trovando chiusa la chiesa va in escandescenza e tenta di darsi fuoco e d\u00e0 fuoco all\u2019auto del parroco<\/p>\n","protected":false},"author":61,"featured_media":170199,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-170198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/170198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=170198"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/170198\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/170199"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=170198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=170198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=170198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}