{"id":170895,"date":"2022-06-13T08:46:47","date_gmt":"2022-06-13T06:46:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/deteneva-15-cani-in-pessime-condizioni-denunciata\/"},"modified":"2023-01-16T17:07:26","modified_gmt":"2023-01-16T16:07:26","slug":"459918-deteneva-15-cani-in-pessime-condizioni-denunciata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/459918-deteneva-15-cani-in-pessime-condizioni-denunciata\/","title":{"rendered":"Deteneva 15 cani in pessime condizioni, denunciata"},"content":{"rendered":"<p>SQUILLACE (CZ) &#8211; Una donna \u00e8 stata denunciata dai <strong>carabinieri<\/strong> della stazione di <strong>Squillace<\/strong>, in seguito a mirati controlli disposti dall&#8217;Autorit\u00e0 giudiziaria che hanno accertato la detenzione di cani tenuti in pessime condizioni.\u00a0Nel dettaglio sono stati ritrovati <strong>15 cani<\/strong>, di cui solo <strong>due erano dotati di microchip,<\/strong> molti dei quali gravemente malati e tutti tenuti in pessime condizioni igienico sanitarie. Alcuni cani erano affetti da <strong>rogna sarcoptica<\/strong>, altri di <strong>pediculosi <\/strong>(infestazione da pidocchi). I cani erano fortemente <strong>emaciati <\/strong>e presentavano\u00a0<strong>dermatiti<\/strong> a causa delle <strong>gravi infestazioni parassitarie<\/strong>. Anche l\u2019abitazione non \u00e8 risultata essere abitabile in quanto non erano presenti i <strong>criteri minimi di igiene<\/strong>. I militari hanno proceduto al sequestro amministrativo dei cani che sono stati trasportati presso il canile di Torre Melissa. L&#8217;operazione dei militari \u00e8 culminata con il sequestro amministrativo dei cani prontamente portati presso il canile di Torre Melissa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cani tenuti in pessime condizioni e alcuni anche malati. I carabinieri hanno denunciato una donna e sequestrato gli animali<\/p>\n","protected":false},"author":22,"featured_media":170896,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-170895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/170895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=170895"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/170895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/170896"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=170895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=170895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=170895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}