{"id":171336,"date":"2022-06-20T16:00:06","date_gmt":"2022-06-20T14:00:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-scelte-data-e-location-del-ritiro-sara-nelle-marche-in-provincia-di-macerata\/"},"modified":"2023-01-16T17:07:56","modified_gmt":"2023-01-16T16:07:56","slug":"461182-cosenza-scelte-data-e-location-del-ritiro-sara-nelle-marche-in-provincia-di-macerata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/461182-cosenza-scelte-data-e-location-del-ritiro-sara-nelle-marche-in-provincia-di-macerata\/","title":{"rendered":"Cosenza, scelte data e location del ritiro. Sar\u00e0 nelle Marche in provincia di Macerata"},"content":{"rendered":"<p>COSENZA &#8211; I <strong>lupi<\/strong> ripartono dalla provincia di <strong>Macerata<\/strong>, precisamente da <strong>Sarnano<\/strong>, dove si aprir\u00e0 il lungo percorso che successivamente porter\u00e0 alla stagione 2022\/2023. La notizie era stata anticipata dal DS Gemmi nella <a href=\"https:\/\/quicosenza.it\/news\/15407\">conferenza stampa<\/a> di venerd\u00ec ed ora la societ\u00e0 rossoblu l&#8217;ha resa ufficiale con un comunicato nel quale spiega le tempistiche. &#8220;Il primissimo ritiro dei rossobl\u00f9 sotto la guida del <strong>neo allenatore Davide Dionigi<\/strong> &#8211; si legge &#8211; si terr\u00e0 nello splendido scenario del <strong>Parco dei Monti Sibillini<\/strong>. L&#8217;iniziativa \u00e8 stata possibile grazie alla coordinazione con Media Sport Event, societ\u00e0 che negli anni ha maturato diversa esperienza nel campo dell&#8217;organizzazione di eventi sportivi. L&#8217;<strong>Hotel Eden ospiter\u00e0 i lupi <\/strong>e il gruppo squadra svolger\u00e0 le sedute di allenamento presso lo <strong>Stadio Maurelli<\/strong>. Il programma prevede l&#8217;inizio del raduno l&#8217; 8 luglio, i bruzi si fermeranno nelle marche fino a domenica 24 luglio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sar\u00e0 Sarnano in provincia di Macerata la sede del ritiro del Cosenza Calcio in vista della nuova stagione di Serie B. Raduno in programma l&#8217;8 luglio<\/p>\n","protected":false},"author":24,"featured_media":171337,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[19],"class_list":["post-171336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/171336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=171336"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/171336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/171337"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=171336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=171336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=171336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}