{"id":171438,"date":"2022-06-22T08:46:30","date_gmt":"2022-06-22T06:46:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/fermato-ad-un-controllo-arrestato-in-spagna-il-boss-vittorio-raso\/"},"modified":"2023-01-16T17:08:02","modified_gmt":"2023-01-16T16:08:02","slug":"461497-fermato-ad-un-controllo-arrestato-in-spagna-il-boss-vittorio-raso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/461497-fermato-ad-un-controllo-arrestato-in-spagna-il-boss-vittorio-raso\/","title":{"rendered":"Fermato ad un controllo, arrestato in Spagna il boss Vittorio Raso"},"content":{"rendered":"<p>ROMA &#8211; Vittorio Raso, considerato boss della &#8216;Ndrangheta, \u00e8 stato fermato nel corso di un controllo stradale di routine, mentre guidava con documenti falsi. Arrestato <strong>una prima volta in Spagna, nel 2020<\/strong>, venne poi rilasciato su ordine di un giudice, e da allora era<strong> latitante.<\/strong>\u00a0 Raso era stato arrestato una prima volta nell&#8217;ottobre del 2020 a Barcellona: la polizia gli attribuiva reati di appartenenza ad <strong>organizzazione criminale, usura e traffico di stupefacenti<\/strong>, considerandolo un personaggio di spicco della &#8216;ndrangheta calabrese radicata a Torino. Pochi giorni dopo per\u00f2, il <strong>tribunale dell&#8217;Audiencia Nacional lo rilasci\u00f2<\/strong>, affermando di non avere elementi sufficienti per ordinare il carcere preventivo nei suoi confronti (in quanto nel verbale a disposizione appariva solo la contestazione di un reato di usura).<\/p>\n<p>Una valutazione &#8211; scrive El Pa\u00eds &#8211; che lasci\u00f2 stupefatta la Polizia Nazionale spagnola. In seguito, l&#8217;Audiencia Nacional emesse un nuovo ordine d&#8217;arresto nei confronti di Raso, che nel frattempo aveva per\u00f2 gi\u00e0 fatto perdere le proprie tracce. A gennaio di quest&#8217;anno, la polizia italiana ha sequestrato in un garage di Nichelino (Torino) oltre <strong>400mila euro<\/strong> in contanti, insieme a <strong>orologi Rolex e gioielli dal valore di oltre 200mila euro<\/strong>, un <strong>&#8216;tesoro&#8217; attribuito proprio a Raso.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; stato arrestato ieri sera dalla polizia locale nel municipio catalano di Castelldefels (Spagna): lo riporta il quotidiano El Pa\u00eds<\/p>\n","protected":false},"author":42,"featured_media":171439,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[22],"tags":[19],"class_list":["post-171438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dal-mondo","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/171438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=171438"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/171438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/171439"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=171438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=171438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=171438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}