{"id":171494,"date":"2022-07-02T05:30:43","date_gmt":"2022-07-02T03:30:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/centri-estivi-a-castrolibero-special-summer-camp-2022-dal-4-luglio\/"},"modified":"2023-01-16T17:08:07","modified_gmt":"2023-01-16T16:08:07","slug":"461661-centri-estivi-a-castrolibero-special-summer-camp-2022-dal-4-luglio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/461661-centri-estivi-a-castrolibero-special-summer-camp-2022-dal-4-luglio\/","title":{"rendered":"Centri estivi a Castrolibero, &#8220;Special Summer Camp 2022&#8221; dal 4 luglio"},"content":{"rendered":"<p>CASTROLIBERO (CS) &#8211; &#8220;Il campo estivo che attiveremo presto a Castrolibero nel periodo di chiusura delle scuole rappresenta un\u2019opportunit\u00e0 sia per le famiglie in cui i genitori possono essere impegnati per lavoro sia per i pi\u00f9 giovani che possono vivere importanti momenti di socializzazione mancati in questi ultimi anni per effetto dell\u2019emergenza sanitaria\u201d. Cos\u00ec <strong>Anna Giulia Mannarino<\/strong>, consigliera comunale di Castrolibero con delega alle Politiche sociali ha annunciato l&#8217;attivazione del servizio &#8220;dall\u2019alta valenza educativa e sociale che sta particolarmente a cuore all\u2019amministrazione e, rispetto al quale, sono state investite delle risorse per i nostri cittadini pi\u00f9 giovani, che sono il nostro futuro, in modo tale da affiancare e sostenere le famiglie, specialmente in questo momento storico difficile&#8221;.<\/p>\n<p>&#8220;Il servizio dello \u2018<strong>Special Summer Camp 2022<\/strong>\u2019 partir\u00e0 dal <strong>4 luglio prossimo al 5 agosto e dall\u20191 al 9 settembre<\/strong>, dalle <strong>8:00 del mattino alle 14:00.<\/strong> Sono previste <strong>gite fuori porta<\/strong> (mare, montagna, visita visite alla fattoria didattica, acquapark) e attivit\u00e0 laboratoriali con associazioni del territorio. Il <strong>costo del campo estivo<\/strong> \u2013 continua la consigliera &#8211; <strong>varia in base alle fasce di reddito<\/strong> e tutte le relative informazioni si possono trovare sulla pagina internet istituzionale del Comune di Castrolibero&#8221;.<\/p>\n<p>&#8220;L\u2019estate \u00e8 lunga, per cui le iniziative di incontro e le attivit\u00e0 ludico-educative sono un bel modo per trascorrere le giornate e permettono a bambini e ragazzi di crescere e confrontarsi sotto la guida degli educatori e del personale qualificato che gestisce il centro di aggregazione sociale. Un ringraziamento in particolare \u2013 conclude Anna Giulia Mannarino &#8211; va al <strong>sindaco Giovanni Greco<\/strong> per aver accolto il progetto da me proposto agli uffici dei servizi sociali e alla responsabile del segretariato sociale per la fattiva collaborazione e il lavoro fatto insieme affinch\u00e9 tutto possa partire\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anna Giulia Mannarino, consigliera comunale di Castrolibero: &#8220;vogliamo sostenere famiglie e ragazzi&#8221;<\/p>\n","protected":false},"author":42,"featured_media":171495,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,564],"tags":[],"class_list":["post-171494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-castrolibero"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/171494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=171494"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/171494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/171495"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=171494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=171494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=171494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}