{"id":17183,"date":"2013-02-06T08:13:26","date_gmt":"2013-02-06T07:13:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=17183"},"modified":"2023-01-17T13:15:12","modified_gmt":"2023-01-17T12:15:12","slug":"6043-sanguinante-e-senza-documenti-sono-caduto-ma-i-medici-non-gli-credono","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6043-sanguinante-e-senza-documenti-sono-caduto-ma-i-medici-non-gli-credono\/","title":{"rendered":"Sanguinante, privo di documenti: &#8220;Sono caduto&#8221;, i medici non gli credono"},"content":{"rendered":"<p><strong>COSENZA<\/strong><strong>&#8211;<\/strong> Un senzatetto dai tratti somatici dell&#8217;Est \u00e8 stato ritrovato alle 03.15 di stanotte dietro l&#8217;ospedale di Cosenza in un bagno di sangue.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Ricoverato nel nosocomio cittadino l&#8217;uomo, ancora in stato di incoscienza, afferma di essere caduto nel cuore della notte. I medici dell&#8217;Annunziata sospettano invece un pestaggio. Il clochard, dal volto tumefatto, presenta un esteso trauma cranico, escoriazioni alle braccia che secondo il personale medico sarebbero indizi di colluttazione poco compatibili con una caduta anche se violenta. Oltre alle ferite sanguinati l&#8217;uomo pare presentasse un tasso alcolemico estremamente elevato. Al suo risveglio sar\u00e0 interrogato dai carabinieri operanti nell&#8217;Ospedale dell&#8217;Annunziata. Intanto le forze dell&#8217;ordine stanno lavorando per rintracciare la persona cui numero di telefono \u00e8 stato rinvenuto in un biglietto che il migrante conservava gelosamente nella tasca dei pantaloni. &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA&#8211; Un senzatetto dai tratti somatici dell&#8217;Est \u00e8 stato ritrovato alle 03.15 di stanotte dietro l&#8217;ospedale di Cosenza in un bagno di sangue.<\/p>\n","protected":false},"author":22,"featured_media":17184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-17183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=17183"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17183\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/17184"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=17183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=17183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=17183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}