{"id":171939,"date":"2022-06-30T14:10:20","date_gmt":"2022-06-30T12:10:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/gerace-porta-del-sole-presentato-il-progetto-per-valorizzare-uno-dei-borghi-piu-belli\/"},"modified":"2023-01-16T17:08:36","modified_gmt":"2023-01-16T16:08:36","slug":"462770-gerace-porta-del-sole-presentato-il-progetto-per-valorizzare-uno-dei-borghi-piu-belli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/462770-gerace-porta-del-sole-presentato-il-progetto-per-valorizzare-uno-dei-borghi-piu-belli\/","title":{"rendered":"\u201cGerace porta del sole\u201d, presentato il progetto per valorizzare uno dei borghi pi\u00f9 belli"},"content":{"rendered":"<p>CATANZARO- La Regione Calabria ha reso pubblico il pr<strong>ogetto che coinvolge la candidatura per il finanziamento dal valore di 20 milioni per Gerace<\/strong>. Questo importante traguardo rappresenterebbe un punto di svolta per tutto il panorama turistico calabrese, il decreto di concessione da parte del<strong> Ministero della Cultura<\/strong> rappresenterebbe un grande passo avanti per poter<strong> valorizzare un dei borghi pi\u00f9 affascinanti<\/strong>, che conserva un centro storico dal grande valore storico, di epoca medioevale. A questo proposito l&#8217;assessore regionale allo Sviluppo economico e Attrattori culturali, Rosario Var\u00ec, ha illustrato in Cittadella a Catanzaro, la conferenza stampa del progetto che ha lo scopo di una rigenerazione culturale, sociale ed economica dal titolo \u201c<strong>Gerace, porta del sole&#8221;<\/strong>, organizzato in risposta all&#8217;invito indirizzato dal Ministero della Cultura alla candidatura di un borgo per regione da finanziare nell\u2019ambito delle risorse del Piano nazionale di ripresa e resilienza.<\/p>\n<p>\u201c<strong>La notizia del decreto di concessione del finanziamento di 20 milioni di euro da parte del Ministero della Cultura<\/strong> rappresenta il raggiungimento di un importante obiettivo\u00a0 &#8211; ha spiegato Var\u00ec\u00a0 &#8211; perseguito mediante la partecipazione al bando ministeriale Pnrr sulla linea A dei borghi nell\u2019ambito del quale<strong> il Governo regionale ha candidato Gerace<\/strong> come destinatario dell\u2019intervento, luogo che ha mantenuto nel tempo la riconoscibilit\u00e0 della sua struttura insediativa storica. Abbiamo atteso \u2013 ha aggiunto l&#8217;assessore \u2013 che si compisse questa formalit\u00e0 amministrativa per presentare oggi gl<strong>i interventi previsti nel progetto finanziato<\/strong>, che ha come finalit\u00e0 la rigenerazione culturale economica e sociale del borgo puntando sull\u2019identit\u00e0 territoriale che diviene attrattore culturale per costruire un modello di sviluppo economico, generatore di rilancio occupazionale e di attrattivit\u00e0 residenziale. Si tratta di una serie di interventi volti al recupero ed alla valorizzazione di edifici, a migliorare l\u2019accessibilit\u00e0 del borgo, all\u2019erogazione di servizi turistici, culturali e di animazione, formativi e di incentivi alle imprese. Tutte azioni queste, volte allo sviluppo territoriale delle quali beneficer\u00e0 non solo Gerace ma tutta la nostra Regione\u201d.<\/p>\n<p>\u201cTre le parole chiave \u2013 ha aggiunto infine Var\u00ec \u2013 ri<strong>generare, ripopolare e valorizzare il grande patrimonio di storia, arte, cultura e tradizioni di questo borgo,<\/strong> facendolo diventare una ricchezza condivisa\u201d. Le attivit\u00e0 tecnico-amministrative di applicazione dei criteri per la selezione del borgo &#8211; indicati dal MiC \u2013 e di redazione progettuale sono state svolte dal Dipartimento Sviluppo economico e Attrattori culturali e dal Comune di Gerace.<\/p>\n<p>Durante\u00a0 l&#8217;evento \u00e8 intervenuto anche l&#8217;assessore alla Cultura, Salvatore Galluzzo, dichiarando: \u201cl\u2019Amministrazione comunale di Gerace\u00a0 \u2013 ringrazia il <strong>presidente Occhiuto, l\u2019assessore Var\u00ec<\/strong> e il suo staff tecnico per il lavoro e il supporto prezioso. Siamo sicuri che la nostra citt\u00e0 sapr\u00e0 cogliere questa grande opportunit\u00e0 per rendere <strong>Gerace meta ancora di pi\u00f9 appetibile a livello turistico e culturale<\/strong>, sia a livello nazionale che internazionale\u201d. Sono intervenuti anche il direttore generale del Dipartimento Sviluppo economico e Attrattori culturali, Fortunato Varone, e la dirigente di settore, Carmen Barbalace. Per Varone si tratta \u201cdi un grande progetto che parte dalle peculiarit\u00e0 di un territorio per esaltarle. Un risultato importante ottenuto grazie ad un lavoro intenso. In questo Dipartimento ho trovato una squadra di professionisti eccellenti che mi onoro di dirigere. \u00c8 stato realizzato un <strong>grande lavoro in perfetta sinergia<\/strong> \u2013 ha aggiunto Barbalace \u2013. Il Piano Nazionale si basa sulla \u2018resilienza\u2019 che \u00e8 quella che mettiamo in campo tutti noi, con l&#8217;attesa e l&#8217;aspettativa di valorizzare al meglio i nostri attrattori culturali, affinch\u00e9 la regione Calabria venga conosciuta e apprezzata per come merita\u201d.<\/p>\n<h4>Il Progetto<\/h4>\n<p>\u201cGerace, porta del sole\u201d si suddivide in <strong>nove interventi mirati<\/strong> che risponderanno alle esigenze della comunit\u00e0 e del visitatore\/turista. I 20 milioni del progetto verranno ripartiti in diverse azioni che hanno lo scopo di riqualificare determinate zone:<\/p>\n<p>sarebbero\u00a0 stanziati 600 mila euro per l&#8217;Artinborgo Festival: con lo scopo di potenziare il festival <strong>\u201cIl borgo Incantato: l\u2019arte di strada nei vicoli\u201d<\/strong> che \u00e8 ormai un appuntamento fisso dal 1999 con ulteriori eventi volti alla valorizzazione del <strong>patrimonio storico e architettonico<\/strong>, del sistema produttivo locale e dell\u2019identit\u00e0 locale in chiave partecipativa.<\/p>\n<p>Per l&#8217; Hub Creativit\u00e0 Mediterranea verrebbero usati 1,5 milioni di euro : si prevedono due laboratori, il primo di restauro, dove i beni culturali del borgo diventeranno un laboratorio per giovani, universit\u00e0, accademie di belle arti e associazioni locali; il secondo di artigianato che punta ad essere un luogo di studio, ricerca e apprendimento delle tradizioni manifatturiere artigianali. All&#8217;<strong>Hub formazione turistica<\/strong> andrebbero <strong>600 mila euro<\/strong> :\u00a0 per il recupero e l&#8217;adeguamento dei locali ex-mattatoio e dello spazio esterno chiostro del Convento della <strong>Chiesa di San Francesco d&#8217;Assisi<\/strong> da adibire a spazio all\u2019aperto per eventi, workshop, networking e corsi di formazione per accompagnatori turistici. <strong>All&#8217;Albergo diffuso ben 7,7 milioni di euro<\/strong>: per il riuso e l&#8217;adeguamento di abitazioni con la realizzazione di <strong>160 posti letto luxury<\/strong>, servizi di <strong>wellness spa e co-working con \u201cart space\u201d<\/strong> in cui ogni stanza\/spazio diventa luogo anche di esposizione artistica. Per il piano<strong> accessibilit\u00e0 fisica<\/strong> sono previsti dei fondi che ammontano a ben <strong>3 milioni di euro<\/strong> : per l&#8217;accesso facilitato al borgo e per la limitazione veicolare del traffico nel centro storico.<strong> Al Sistema di illuminazione<\/strong> integrato dei fondi pari a<strong> 800 mila euro<\/strong>: impianti di illuminazione decorativa e artistica per i monumenti. Al <strong>servizio Gerace porta digitale<\/strong> andrebbero cos\u00ec<strong> 600 mila euro<\/strong>: per i <strong>servizi digitali<\/strong> indirizzati alla fruizione del patrimonio artistico e culturale. Per gli incentivi per lo sviluppo : incentivi per <strong>PMI e nuove imprese femminili e giovanili e imprese del terzo settore<\/strong> operanti in ambito culturale, artistico, turistico, ricreativo, sociale. Il piano prevede ben 1.2 milioni di euro per il Marketing territoriale: con la <strong>proposta di candidatura del borgo a patrimonio Unesco<\/strong>; attivit\u00e0 di formazione e capacity building per migliorare le potenzialit\u00e0 espresse e inespresse del territorio e l\u2019accoglienza turistica; attivit\u00e0 i comunicazione e promozione delle risorse artigianali e turistiche.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un progetto finanziato con 20 milioni di euro per &#8220;ingenerare, ripopolare e valorizzare il grande patrimonio di storia, arte, cultura e tradizioni&#8221;<\/p>\n","protected":false},"author":68,"featured_media":171940,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-171939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/171939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=171939"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/171939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/171940"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=171939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=171939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=171939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}