{"id":172274,"date":"2022-07-06T10:50:00","date_gmt":"2022-07-06T08:50:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ss-106-sibari-corigliano-rossano-il-tratto-della-discordia\/"},"modified":"2023-01-16T17:08:57","modified_gmt":"2023-01-16T16:08:57","slug":"463698-ss-106-sibari-corigliano-rossano-il-tratto-della-discordia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/463698-ss-106-sibari-corigliano-rossano-il-tratto-della-discordia\/","title":{"rendered":"SS 106, Sibari-Corigliano Rossano: il tratto della discordia"},"content":{"rendered":"<p>Lo scorso mese di dicembre <strong>Anas<\/strong> aveva addirittura presentato il progetto dei lavori di ammodernamento del tratto <strong>Sibari-Rossano della Strada Statale 106 Ionica<\/strong>. Da allora, per\u00f2, non sono iniziati i lavori, ma lo scontro fra Anas ed i comuni interessati dall&#8217;opera. Non c&#8217;\u00e8 ancora una soluzione per la vicenda relativa al percorso del tratto, che dovr\u00e0 essere oggetto dei lavori in questione.<br \/>\nLa situazione, quindi, \u00e8 indefinita gi\u00e0 da mesi: il pomo della discordia riguarda, ora, il percorso nel Comune di <strong>Corigliano Rossano<\/strong>. Il sindaco del comune ionico, <strong>Flavio Stasi<\/strong>, avrebbe optato per<strong> un percorso lontano dal centro abitato<\/strong>, al contrario di quanto prospettato da Anas, che avrebbe previsto il tratto pi\u00f9 a valle. Una divergenza di opinioni che, secondo alcuni parlamentari, avrebbe causato la perdita di fondi, che il Governo avrebbe utilizzato per coprire l&#8217;aumento dei costi delle materie prime in altri cantieri gi\u00e0 avviati.<br \/>\nLa novit\u00e0, adesso, riguarda una soluzione prospettata da Anas e Regione Calabria, che avrebbero proposto la realizzazione di<strong> un sottopasso nell&#8217;area urbana di Rossano<\/strong>. Un qualcosa che sarebbe stata ritenuta di facile attuazione e senza minare l&#8217;assetto e la conformazione territoriale.<br \/>\nLa palla passa ora al comune che dovr\u00e0 dare una risposta per chiudere eventualmente la vicenda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da diversi mesi si cerca una soluzione che possa accontentare Anas ed i comuni interessati. E mentre si valutano le proposte sulla SS 106 si continua a morire<\/p>\n","protected":false},"author":65,"featured_media":172275,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19,135],"class_list":["post-172274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina","tag-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/172274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=172274"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/172274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/172275"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=172274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=172274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=172274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}