{"id":172502,"date":"2022-07-10T09:43:11","date_gmt":"2022-07-10T07:43:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/caso-valentini-majorana-la-cgil-replica-ai-legali-della-dirigente-non-ci-zittirete\/"},"modified":"2023-01-16T17:09:13","modified_gmt":"2023-01-16T16:09:13","slug":"464376-caso-valentini-majorana-la-cgil-replica-ai-legali-della-dirigente-non-ci-zittirete","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/464376-caso-valentini-majorana-la-cgil-replica-ai-legali-della-dirigente-non-ci-zittirete\/","title":{"rendered":"Caso &#8220;Valentini-Majorana&#8221;, Assalone replica ai legali della dirigente \u00abnon ci zittirete\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;\u00c8 evidente che ha dato molto fastidio il nostro riaccendere i riflettori su una vicenda tanto assurda e dai contorni sempre pi\u00f9 rocamboleschi, che sembrava essere stata messa nel cassetto del dimenticatoio. E cos\u00ec \u00e8 spuntato<strong><a href=\"https:\/\/quicosenza.it\/news\/15568\" target=\"_blank\" rel=\"noopener\"> l\u2019aut-aut \u00a0dei difensori<\/a><\/strong> della Dirigente scolastica del \u201cValentini-Majorana\u201d di Castrolibero che come avvoltoi <strong>annunciano \u00a0di colpire chi volesse compromettere quel silenzio<\/strong> ormai ritenuto acquisito e che non potrebbe essere messo in discussione da eventuali reazioni o da dichiarazioni critiche&#8221;. Cos\u00ec replica in una nota stampa <strong>Pino Assalone, coordinatore di Democrazia e Lavoro &#8211; Sinistra Cgil<\/strong>, dopo l&#8217;intervento degli avvocati <strong>Enzo Belvedere e Pasquale Naccarato<\/strong> in merito al caso riguardante le presunte molestie al Liceo Valentini-Majorana di Castrolibero.<\/p>\n<p>&#8220;La domanda che come Sinistra CGIL abbiamo posto con forza \u00e8 stata se fosse opportuno da parte dell\u2019Amministrazione scolastica consentire il ritorno a scuola della DS tanto contestata a distanza di qualche mese dal suo pensionamento che dovrebbe avvenire da settembre del 2022 o se invece per ragioni di opportunit\u00e0 sarebbe stato utile evitarlo. Secondo la nota degli avvocati, porsi questa domanda dovrebbe essere ci\u00f2 che lede il buon nome della dirigente scolastica ed \u00e8 per questo,<strong> fanno sapere, che si pu\u00f2 essere perseguiti ai sensi di legge<\/strong>. \u00a0Agli esimi avvocati dovremmo chiedere quanti in questa vicenda siano stati veramente e fortemente lesi nella loro immagine, a partire dalla comunit\u00e0 scolastica e dalla societ\u00e0 locale tutta, che hanno vissuto come una doccia fredda una vicenda che ha sconvolto le coscienze e la sensibilit\u00e0 di quanti hanno a cuore l\u2019istituzione scolastica come comunit\u00e0 educante.<\/p>\n<p>Forse qualcuno pensa che quanto accaduto sia avvenuto per mano di qualche sciacallo, qualche stregone o sciamano o addirittura attraverso qualche sortilegio. \u00a0Un mese di proteste da parte degli studenti, l\u2019interesse della stampa nazionale, gli interventi di esponenti politici e di qualche sindacato, l\u2019affondo del Garante per l\u2019Infanzia: non sono stati certamente loro i costruttori di eventuali congiure e gli architetti di una messa in scena operata per colpire qualcuno. \u00a0Gli avvocati hanno tutto il diritto di difendere chiunque si rivolga loro. Il mio non vuole essere naturalmente un linguaggio giuridico, &#8211; prosegue Assalone &#8211; che non mi appartiene, ma ritengo assolutamente <strong>doveroso difendere il mio pensiero e le mie ragioni<\/strong>, provando ad esprimerlo con il confronto democratico in ogni modo e manifestazione. E ritengo che quanto accaduto in quella scuola di Castrolibero non possa essere esclusivo dibattito relegato nelle stanze di un tribunale. N\u00e9 censurato.<\/p>\n<p>In quella scuola a febbraio abbiamo visto esprimersi un <strong>protagonismo partecipato dagli studenti<\/strong> e da quanti hanno dato loro solidariet\u00e0, a cominciare dalla Sinistra CGIL, che non ricercavano \u201cvisibilit\u00e0 mediatica\u201d ma porre questioni ineludibili. Oggi certo non ci indurranno al silenzio le roboanti parole dei due avvocati. Siamo invece fortemente preoccupati perch\u00e9 queste affermazioni potrebbero provocare nei giovani sentimenti di sfiducia, di rassegnazione, di timore nel prendere posizione e reagire rispetto a quel che appare ingiusto, potrebbero persino incoraggiare al silenzio ed alla disaffezione coloro che hanno espresso vicinanza alta e convinta nei loro confronti.<\/p>\n<p>E noi non ci fermeremo. Anzi con caparbiet\u00e0 ed impegno proseguiremo nel confrontarci e dare voce a chi, come noi, ricerca ulteriormente la verit\u00e0 e condivide valori umani e solidali. Gli stessi che si sono espressi nella grande e straordinaria manifestazione cittadina a sostegno delle ragioni di tante studentesse. Il diritto \u00e8 cultura della ragionevolezza e non si pu\u00f2 essere irrispettosi nei confronti di chi manifesta il dissenso. Credo che tante e tanti proveranno a resistere insieme a noi in ogni modo possibile a questa irrazionale e preoccupante deriva.<\/p>\n<p>Personalmente sono e<strong> tutta la Sinistra CGIL siamo dalla parte di coloro che hanno voglia di manifestare contrariet\u00e0<\/strong> &#8211; conclude il sindacalista &#8211; e disappunto rispetto a quanto accade, che non partecipano al coro della retorica istituzionale, al mainstream pi\u00f9 ossequioso, che non si piegano al pensiero unico. Partecipazione democratica ed elaborazione ed espressione del pensiero critico non cesseranno anche su questa vicenda, poco importa se ci\u00f2 inceppa l\u2019armonia dell\u2019ingranaggio tanto amato da chi gestisce la cosa pubblica e da chi ama restare in silenzio per qualche briciola. Dispiace anche per i due legali che hanno scritto quella brutta nota: la tradizione forense della citt\u00e0 \u00e8 ben altro!&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cos\u00ec Pino Assalone interviene dopo la polemica sul ritorno a scuola della preside Maletta nel liceo di Castrolibero al centro di un caso su presunte molestie<\/p>\n","protected":false},"author":58,"featured_media":172503,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-172502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/172502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=172502"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/172502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/172503"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=172502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=172502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=172502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}