{"id":172656,"date":"2022-07-17T17:00:29","date_gmt":"2022-07-17T15:00:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/violenza-contro-le-donne-d-i-re-nel-2021-vittime-aumentate-del-35\/"},"modified":"2023-01-16T17:09:24","modified_gmt":"2023-01-16T16:09:24","slug":"464816-violenza-contro-le-donne-d-i-re-nel-2021-vittime-aumentate-del-35","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/464816-violenza-contro-le-donne-d-i-re-nel-2021-vittime-aumentate-del-35\/","title":{"rendered":"Violenza contro le donne, D.i.Re: &#8220;nel 2021 vittime aumentate del 3,5%&#8221;"},"content":{"rendered":"<p>ROMA &#8211; Sono state 20.711 le donne accolte, nel 2021, nei centri antiviolenza della rete D.i.Re, con un incremento del 3,5% rispetto al 2020. Quasi la met\u00e0, ovvero il 46% delle donne accolte, ha un&#8217;et\u00e0 compresa tra i <strong>30 e i 49 anni<\/strong>. E&#8217; quanto emerge dall&#8217;ultimo report dell&#8217;Associazione nazionale D.i.Re &#8211; Donne in Rete contro la violenza sui dati riferiti al 2021. Le donne, sono prevalentemente italiane (solo il 26% hanno una diversa provenienza), un dato costante negli ultimi anni e anche <strong>l&#8217;autore della violenza \u00e8 prevalentemente italiano<\/strong> (soltanto il 27% ha provenienza straniera). Un dato oramai consolidato negli anni.<\/p>\n<h3>I centri antiviolenza della Rete<\/h3>\n<p>Sono presenti in tutte le regioni italiane, tranne che nel Molise, oltre la met\u00e0 si trovano nell&#8217;area del nord (58 pari al 55%) divisi non equamente tra nord-est e nord-ovest; in quella del centro ci sono 24 centri (pari al 23%) e tra sud (16) e isole (8) si arriva a 24 centri (pari al 23%). <strong>Insieme al numero delle donne accolte<\/strong>, \u00e8 aumentata anche la <strong>risposta che i centri antiviolenza danno sul territorio<\/strong>: le organizzazioni della Rete che hanno partecipato all&#8217;indagine (81 su 82), attraverso i loro 106 Centri antiviolenza, <strong>gestiscono 182 Sportelli antiviolenza con un incremento del 25% rispetto al 2020.<\/strong><\/p>\n<p>Oltre la met\u00e0 dei centri (58,5% dei casi) pu\u00f2 contare su almeno una struttura di ospitalit\u00e0 (62 in totale), con un&#8217;offerta di 185 appartamenti e 1023 posti letto. Le attivit\u00e0 che i Centri garantiscono alle donne sono sempre varie: accoglienza e possibilit\u00e0 di consulenza legale nella quasi totalit\u00e0 dei casi, consulenza psicologica e percorsi di orientamento al lavoro in circa il 90% dei casi.<\/p>\n<p>Nella comparazione con il 2020 emerge un incremento per il servizio di orientamento al lavoro, che passa dall&#8217;88% al 94% dei centri. Questo dato \u00e8 particolarmente significativo &#8211; viene fatto notare &#8211; se si pensa che una donna su tre (31,9% tra disoccupate, casalinghe e studentesse) \u00e8 a reddito zero, in linea con il 2020 (32,9%) e il 2019 (33,8%). Solo il 37% (tra occupate e pensionate) pu\u00f2 contare su un reddito sicuro. Soltanto il 28% delle donne accolte decide di denunciare, percentuale che rimane sostanzialmente costante negli anni. L&#8217;attivit\u00e0 dei centri si sostiene per gran parte sul lavoro volontario delle attiviste, di cui solo il 33, 3% \u00e8 retribuito, anche a causa della scarsit\u00e0 e non strutturalit\u00e0 dei fondi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-450840 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/04\/antonella-veltri-d.i.re_..jpg\" alt=\"\" width=\"439\" height=\"272\" title=\"\"><\/p>\n<h4>Veltri: &#8220;non basta Piano antiviolenza se mancano linee guida attuative&#8221;<\/h4>\n<p>&#8220;20.711 donne nel 2021, il 3,5% di contatti in pi\u00f9 rispetto al 2020, l&#8217;8,8% in pi\u00f9 le donne che non avevano mai chiamato il Centro antiviolenza, sono <strong>numeri che confermano l&#8217;importanza dei centri della nostra Rete<\/strong>. <strong>Dietro ogni numero c&#8217;\u00e8 una storia,<\/strong> la storia di ogni singola donna, che crede nella possibilit\u00e0 di uscire dalla violenza, d\u00e0 fiducia ai nostri centri: l&#8217;aumento di donne che a noi si rivolgono lo leggiamo in questa luce&#8221;. E&#8217; il commento di Antonella Veltri, Presidente D.i.Re &#8211; Donne in Rete contro la violenza.<\/p>\n<p>&#8220;Sono numeri che <strong>danno la misura<\/strong> &#8211; sottolinea &#8211;<strong> del lavoro che le 2.793 attiviste<\/strong>, di cui solo poco pi\u00f9 del 30% retribuite, <strong>svolgono per dare forza alle donne.<\/strong> Non basta per\u00f2 &#8211; spiega Veltri &#8211; approvare un Piano antiviolenza se mancano le linee guida attuative: siamo in attesa di questo, <strong>dell&#8217;impegno concreto del governo sul tema della violenza maschile alle donne<\/strong>, per il 2021-2023&#8243; .<\/p>\n<p>&#8220;La fotografia annuale che presentiamo ci conferma che &#8211; conclude la presidente &#8211; i nostri presidi territoriali sono baluardi imprescindibili nella prevenzione e nel contrasto della violenza alle donne. Lavoriamo per le donne e con le donne. Continueremo a farlo perch\u00e9 crediamo nel valore e nel potere che abbiamo di trasformare il modello culturale patriarcale da cui prende origine ogni forma di violenza alle donne&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quasi 21mila donne accolte nei centri antiviolenza solo nel 2021, in prevalenza italiane. E sono italiani anche gli autori<\/p>\n","protected":false},"author":42,"featured_media":172657,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-172656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/172656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=172656"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/172656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/172657"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=172656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=172656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=172656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}