{"id":172725,"date":"2022-07-14T07:04:58","date_gmt":"2022-07-14T05:04:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/da-scalea-a-palo-alto-per-creare-un-ponte-oltreoceano\/"},"modified":"2023-01-16T17:09:29","modified_gmt":"2023-01-16T16:09:29","slug":"465000-da-scalea-a-palo-alto-per-creare-un-ponte-oltreoceano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/465000-da-scalea-a-palo-alto-per-creare-un-ponte-oltreoceano\/","title":{"rendered":"Da Scalea a Palo Alto per creare un &#8220;ponte&#8221; oltreoceano"},"content":{"rendered":"<p>SCALEA (CS) &#8211; Un collegamento con la citt\u00e0 californiana grazie alla passione per la bicicletta che unisce i \u201cTer\u00f9n\u201d di tutto il mondo. Ter\u00f9n \u00e8 infatti uno dei ristoranti che Maico e Franco Campilongo hanno aperto in California grazie ai quali hanno fatto innamorare della cucina e della cultura italiana tutta la Silicon Valley, ma \u00e8 anche il nome dell\u2019ormai celebre squadra ciclistica amatoriale fondata a Palo Alto e che, con la costola di Scalea, promuove da anni il <strong>cicloturismo<\/strong> favorendo la conoscenza diretta del territorio della Riviera dei Cedri a tanti appassionati del \u201cbike turism\u201d statunitense.<\/p>\n<p>La suggestione di creare un vero e proprio <strong>ponte tra la citt\u00e0 di Scalea e quella di Palo Alto<\/strong> \u00e8 nata nei mesi scorsi, quando <strong>Maico e Franco, di ritorno a Scalea<\/strong> per assistere dal vivo all\u2019arrivo della sesta tappa del giro d\u2019Italia proprio nella citt\u00e0 dalla quale sono partiti anni fa direzione USA, hanno proposto al sindaco Giacomo Perrotta di costruire un rapporto istituzionale tra la Riviera dei Cedri e la Silicon Valley. Detto fatto, e alla prima occasione utile, il viaggio in Europa del Sindaco Patrick Burt con sua moglie Sally, due giorni sono stati dedicati a Scalea.<\/p>\n<p>Una prima visita per conoscere il territorio, apprezzarne le caratteristiche climatiche e paesaggistiche e immaginare i possibili scenari futuri nell\u2019ottica turistica, delle contaminazioni di idee e anche per ipotizzare una sorta di fenomeno migratorio verso la <strong>Riviera dei Cedri<\/strong> da dove poter lavorare in \u201csmart working\u201d, godere di un ritmo meno frenetico per innalzare la qualit\u00e0 della vita e, al contempo, portare sul territorio contaminazioni culturali e, perch\u00e9 no, iniziative imprenditoriali per dare a Scalea una dimensione internazionale non solo dal punto di vista turistico ma anche sotto quello residenziale. Un\u2019idea che da anni frulla nella testa dei fratelli Maico e Franco Campilongo, insieme a Giuseppe Errico e Rossano Bruno quella del \u201cponte\u201d tra la citt\u00e0 di Palo Alto e Scalea.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-465003 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/07\/scalea-palo-alto-sindaci-03.jpg\" alt=\"\" width=\"467\" height=\"289\" title=\"\"><\/p>\n<p>Dal <strong>gemellaggio tra la Squadra Ter\u00f9n Scalea e la squadra di San Francisco passando per la Granfondo Ter\u00fan<\/strong> e tanti altri progetti per promuovere il cicloturismo che gi\u00e0 a giugno ha portato un nutrito gruppo di appassionati statunitensi nella riviera dei Cedri, il passo verso un gemellaggio istituzionale potrebbe essere pi\u00f9 breve di quanto si potesse sperare.<\/p>\n<p>\u201cA Palo Alto &#8211; ha dichiarato Patrick Burt &#8211; abbiamo dei grandissimi amici di Scalea, Franco e Maico i quali hanno portato un pezzo di Italia, di Calabria e di Scalea in California. Non soltanto il cibo italiano ma il modo di fare e di essere li hanno immediatamente fatti apprezzare da tutta la comunit\u00e0. Scalea ha un mare bellissimo, un centro storico meraviglioso e le persone sono calorosissime. Ci sono delle differenze evidente tra Scalea e Palo Alto ma anche delle analogie come la passione con la quale vengono portate avanti le iniziative: in California l\u2019hi-tech e tutto ci\u00f2 che \u00e8 innovazione,<strong> a Scalea il turismo, l\u2019accoglienza e la cultura del buon cibo<\/strong>. Penso che si possa creare una stretta relazione tra le due comunit\u00e0 nonostante le distanze perch\u00e9 in Silicon Valley la vita \u00e8 molto costosa ma con la possibilit\u00e0 offerta dall\u2019home working molte persone potrebbero decidere di trasferirsi in questi luoghi senza rinunciare ai redditi percepiti dalle grosse compagnie ma innalzando di gran lunga la qualit\u00e0 della vita\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-465002 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/07\/scalea-palo-alto-sindaci-02.jpg\" alt=\"\" width=\"478\" height=\"296\" title=\"\"><\/p>\n<p>\u201cQuesta visita rappresenta &#8211; ha commentato Giacomo Perrotta primo cittadino di Scalea &#8211; un avvenimento straordinario, un piccolo passo che ci porter\u00e0 a tessere dei rapporti sempre pi\u00f9 stretti con la citt\u00e0 di Palo Alto grazie soprattutto a Maico e Franco Campilongo che hanno reso possibile questo collegamento. E\u2019 realmente un sogno vedere che Scalea allarga i suoi confini fino al di l\u00e0 dell\u2019oceano portando la nostra cultura, il nostro modo di fare, il nostro calore perch\u00e9 gli scaleoti e i calabresi in generale si sanno fa riconoscere e apprezzare ovunque per la loro laboriosit\u00e0, disponibilit\u00e0 e grande gentilezza e voglia di fare. Il sogno di un gemellaggio \u00e8 reale e concreto e lo vogliamo basare sulle possibilit\u00e0 che si stanno creando in ambito di cicloturismo e perch\u00e9 no anche offrendo ospitalit\u00e0 a quanti volessero scegliere Scalea e la Riviera dei Cedri per vivere e lavorare in modalit\u00e0 smart\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-465004 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/07\/scalea-palo-alto-sindaci-04.jpg\" alt=\"\" width=\"583\" height=\"361\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra le citt\u00e0 del Nord Europa e del Mediterraneo che ha scelto di visitare, il sindaco di Palo Alto (California) Patrick Burt ha inserito una tappa a Scalea<\/p>\n","protected":false},"author":42,"featured_media":172726,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[19],"class_list":["post-172725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/172725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=172725"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/172725\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/172726"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=172725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=172725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=172725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}