{"id":17347,"date":"2013-02-07T14:40:33","date_gmt":"2013-02-07T13:40:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=17347"},"modified":"2023-01-17T13:15:21","modified_gmt":"2023-01-17T12:15:21","slug":"6127-si-scambiavano-cocaina-fra-loro-due-arresti-nel-capoluogo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6127-si-scambiavano-cocaina-fra-loro-due-arresti-nel-capoluogo\/","title":{"rendered":"Si scambiavano cocaina fra loro, due arresti nel capoluogo"},"content":{"rendered":"<p><p><strong>CATANZARO<\/strong> &#8211; Tratte in arresto due persone dai Carabinieri di Catanzaro Lido. L&#8217;accusa per i due,&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<p>Domenico Falcone e Gianluca Russo, di 40 e 24 anni, \u00e8 di detenzione illegale a fini di spaccio di cocaina.<\/p>\n<p>Sono stati scoperti durante uno scambio di droga tra loro, confezionata in un unico involucro, contenente 11,7 grammi di cocaina. Falcone, sempre stando alle accuse, aveva appena passato lo stupefacente a Russo che pero&#8217;, accortosi della presenza dei carabinieri, lo ha subito gettato a terra. I due sono stati a quel punto identificati e tratti in arresto in flagranza, e domani compariranno per il rito direttissimo davanti al giudice monocratico, Barbara Fatale, cui il sostituto procuratore di turno, Carlo Villani, ha chiesto la convalida dell&#8217;arresto e l&#8217;applicazione della misura cautelare in carcere &#8220;attesi &#8211; ha evidenziato il magistrato &#8211; i numerosi precedenti&#8221;. In aula Falcone sara&#8217; difeso dall&#8217;avvocato Gregorio Viscomi, mentre Russo da Salvatore Staiano.&nbsp;<\/p>\n<p>&nbsp;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Tratte in arresto due persone dai Carabinieri di Catanzaro Lido. L&#8217;accusa per i due,&nbsp;<\/p>\n","protected":false},"author":22,"featured_media":17348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-17347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=17347"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17347\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/17348"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=17347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=17347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=17347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}