{"id":173480,"date":"2022-07-31T13:00:50","date_gmt":"2022-07-31T11:00:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/alberi-monumentali-mipaaf-aggiorna-lelenco-401-new-entry\/"},"modified":"2023-01-16T17:10:20","modified_gmt":"2023-01-16T16:10:20","slug":"467031-alberi-monumentali-mipaaf-aggiorna-lelenco-401-new-entry","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/467031-alberi-monumentali-mipaaf-aggiorna-lelenco-401-new-entry\/","title":{"rendered":"Alberi Monumentali, Mipaaf: 401 &#8216;new entry&#8217; tra cui il castagno di Sorbo San Basile"},"content":{"rendered":"<p>ROMA &#8211; \u00c8 stato pubblicato sul sito del ministero delle Politiche agricole <a href=\"https:\/\/quicosenza.it\/news\/15734\" target=\"_blank\" rel=\"noopener\">l&#8217;elenco aggiornato degli alberi monumentali d&#8217;Italia<\/a>: <strong>401<\/strong> le nuove iscrizioni, per un totale di <strong>4.006 esemplari censiti<\/strong> per il particolare pregio naturale e culturale. Alberi che rappresentano un patrimonio da tutelare e valorizzare, con esemplari che si contraddistinguono per particolari caratteristiche; come <strong>l&#8217;elevato valore biologico ed ecologico<\/strong> <strong>per et\u00e0<\/strong>, <strong>dimensioni, morfologia, rarit\u00e0 della specie o habitat per alcune specie animali,<\/strong> l&#8217;importanza storica, culturale o religiosa rivestita sul territorio e la capacit\u00e0 di caratterizzare il paesaggio sia in termini estetici che identitari.<\/p>\n<p>Tra le <strong>nuove iscrizioni<\/strong> spiccano per numerosit\u00e0 i <strong>cedri, le querce, i platani e i faggi<\/strong>, mentre fanno la loro prima comparsa nell&#8217;Elenco alcune specie come l&#8217;acero <strong>palmato rosso<\/strong>, la <strong>camelia e l&#8217;anagiride<\/strong>. Per maestosit\u00e0 si contraddistinguono il cedro del libano nel Parco di Villa Mirabello a Varese, con un fusto di oltre 11 metri di circonferenza e un&#8217;ampia chioma che si estende in modo simmetrico e regolare con un diametro di 36 metri, la farnia di Barano d&#8217;Ischia in provincia di Napoli, con una circonferenza di 8,6 metri e un&#8217;et\u00e0 stimata di circa 350 anni, e il <strong>castagno di Sorbo San Basile in provincia di Catanzaro<\/strong>, con un tronco di 8,4 metri di circonferenza e risalente al <strong>1700. <\/strong><\/p>\n<p>L&#8217;Elenco \u00e8 frutto di un&#8217;intensa attivit\u00e0 di catalogazione realizzata in modo coordinato e sinergico da ministero, Regioni e Province autonome e Comuni. Questo aggiornamento, approvato dal Mipaaf con decreto dirigenziale del 26 luglio, tiene conto di cancellazioni e delle nuove iscrizioni proposte dalle Regioni Basilicata, <strong>Calabria<\/strong>, Campania, Friuli Venezia Giulia, Lazio, Liguria, Lombardia, Marche, Molise, Puglia, Sardegna, Sicilia e Veneto e dalla Provincia autonoma di Trento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il ministero delle politiche agricole aggiorna l&#8217;elenco degli oltre 4mila alberi monumentali. Cedri, querce, platani e faggi i pi\u00f9 numerosi<\/p>\n","protected":false},"author":42,"featured_media":173481,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-173480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/173480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=173480"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/173480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/173481"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=173480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=173480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=173480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}