{"id":173514,"date":"2022-07-28T19:41:31","date_gmt":"2022-07-28T17:41:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/violento-incidente-sulla-statale-106-a-mirto-crosia-due-feriti\/"},"modified":"2023-01-16T17:10:22","modified_gmt":"2023-01-16T16:10:22","slug":"467105-violento-incidente-sulla-statale-106-a-mirto-crosia-due-feriti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/467105-violento-incidente-sulla-statale-106-a-mirto-crosia-due-feriti\/","title":{"rendered":"Violento incidente sulla Statale 106 a Mirto Crosia, una vittima"},"content":{"rendered":"<p>MIRTO CROSIA (CS) &#8211; Un incidente stradale si \u00e8 verificato in serata<strong> sulla Statale 106 nel comune di Mirto Crosia<\/strong> ed ha visto coinvolte due auto, <strong>un&#8217;Audi A3<\/strong> e una <strong>Daewoo Matiz<\/strong>. Sul posto \u00e8 intervenuta una squadra dei Vigili del fuoco del comando di Cosenza &#8211; distaccamento di Rossano che ha lavorato per estrarre dalle lamiere <strong>entrambi i conducenti rimasti feriti e affidati alle cure dei sanitari del 118<\/strong>. Le due persone sono state portate in ospedale.<\/p>\n<p>La dinamica \u00e8 in corso d&#8217;accertamento e i vigili del fuoco hanno provveduto a mettere in sicurezza la zona e le vetture. La Statale 106 Jonica, nel tratto interessato dal sinistro, \u00e8 stata <strong>chiusa al transito in entrambi i sensi di marcia<\/strong>. Sul posto i carabinieri per gli adempimenti di competenza e si sono verificati notevoli disagi per la viabilit\u00e0 che \u00e8 stata dirottata su un percorso alternativo.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Aggiornamento alle 22<\/strong><\/span><\/p>\n<p>Il bilancio dell&#8217;incidente si \u00e8 aggravato ed una <strong>donna di 70 anni di Mirto Crosia<\/strong>, coinvolta nell&#8217;impatto \u00e8 deceduta. Si chiamava <strong>Carmela Toscano<\/strong> e viaggiava a bordo della Matiz.<\/p>\n<p>&nbsp;<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Sul posto Vigili del fuoco, sanitari del 118 e  carabinieri. Sul tratto della 106 si sono verificati notevoli disagi per la viabilit\u00e0 che \u00e8 stata dirottata su un percorso alternativo<\/p>\n","protected":false},"author":42,"featured_media":173515,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[19],"class_list":["post-173514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/173514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=173514"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/173514\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/173515"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=173514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=173514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=173514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}