{"id":17401,"date":"2013-02-08T11:17:26","date_gmt":"2013-02-08T10:17:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=17401"},"modified":"2023-01-17T13:15:23","modified_gmt":"2023-01-17T12:15:23","slug":"6154-rinnavato-comitato-tgr-rai-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6154-rinnavato-comitato-tgr-rai-calabria\/","title":{"rendered":"Rinnovato comitato Tgr Rai Calabria"},"content":{"rendered":"<p><strong style=\"font-size: 12px; line-height: 1;\">COSENZA<\/strong><span style=\"font-size: 12px; line-height: 1;\"> &#8211; Rinnovato il Comitato di redazione Tgr Rai Calabria. Hanno partecipato alle elezioni tutti e 26 i giornalisti della Sede Rai calabrese.<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p>Eletti: Carla Monaco (14 voti), Livia Blasi (14 voti), Antonio Lopez (11 voti). Per Carla Monaco si tratta di una conferma. Gli uscenti Dino Gardi e Cesare Passalacqua non si erano ricandidati.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Rinnovato il Comitato di redazione Tgr Rai Calabria. Hanno partecipato alle elezioni tutti e 26 i giornalisti della Sede Rai calabrese.<\/p>\n","protected":false},"author":22,"featured_media":17402,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-17401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=17401"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/17402"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=17401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=17401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=17401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}