{"id":174221,"date":"2022-08-12T04:25:44","date_gmt":"2022-08-12T02:25:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/plastic-free-il-comune-di-praia-a-mare-firma-il-protocollo-di-convenzione\/"},"modified":"2023-01-16T17:11:09","modified_gmt":"2023-01-16T16:11:09","slug":"469124-plastic-free-il-comune-di-praia-a-mare-firma-il-protocollo-di-convenzione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/469124-plastic-free-il-comune-di-praia-a-mare-firma-il-protocollo-di-convenzione\/","title":{"rendered":"&#8220;Plastic Free&#8221;, il Comune di Praia a Mare firma il protocollo di convenzione"},"content":{"rendered":"<p>PRAIA A MARE (CS) &#8211; Il\u00a0<strong>Comune di Praia a Mare<\/strong> ha firmato il protocollo con Plastic Free con i referenti di zon- Si chiude un cerchio importante per l\u2019Alto Tirreno Cosentino per quanto riguarda l<strong>e iniziative di sensibilizzazione alla diminuzione dell\u2019uso della plastica<\/strong> e per le iniziative che hanno come obiettivo la tutela dell\u2019ambiente. Conclusa la parte burocratica, i referenti di zona Antonella Palladino e Carmelo De Leo insieme al consigliere delegato all\u2019ambiente Domenico Droghini, gi\u00e0 programmano le future azioni:\u00a0g<strong>iornate di raccolta ed attivit\u00e0 nelle scuole ma non solo<\/strong>, gli obiettivi vanno oltre e a settembre i primi tavoli di lavoro avranno il privilegio di ospitare il segretario generale di Plastic Free Antonio Rancati.<\/p>\n<div dir=\"auto\">Una settimana in cui il\u00a0 dottor Droghini lavorer\u00e0 in concertazione con i Comuni da Tortora a Diamante, affinch<strong>\u00e9 oltre a sensibilizzare si studino pi\u00f9 a fondo i problemi del territorio ma soprattutto si trovino soluzioni<\/strong>. Il sindaco Antonino De Lorenzo, gi\u00e0 ospite delle iniziative del dottor Rancati al Senato della Repubblica per altre iniziative premiate del nostro territorio, mira alla candidatura di Comune Plastic Free insieme ai Comuni di Tortora e Aieta, nel pieno rispetto delle dinamiche di una politica di comprensorio.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">\u201cLe sinergie ci sono \u2013 spiegano i referenti di zona De Leo e Palladino \u2013 la v<strong>olont\u00e0 non \u00e8 mai mancata, siamo esponenti di tutti i cittadini che fanno gi\u00e0 tanto per la tutela del pianeta, ognuno nel proprio piccolo,<\/strong> con grande senso di responsabilit\u00e0 e senza gesti eclatanti; noi spingiamo solo le fila, manteniamo i cordoli uniti e diamo spunti per migliorarci grazie alla professionalit\u00e0 dei vertici di Plastic Free e di tutti i referenti del territorio. Grazie a tutta l\u2019Amministrazione Comunale di Praia, che ci ha dato fiducia, in particolare al nostro referente delegato all\u2019Ambiente. Cercheremo di fare con determinazione sempre il nostro meglio\u201d.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Iniziative di sensibilizzazione alla diminuzione dell\u2019uso della plastica e che hanno come obiettivo la tutela dell\u2019ambiente<\/p>\n","protected":false},"author":55,"featured_media":174222,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[19],"class_list":["post-174221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/174221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=174221"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/174221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/174222"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=174221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=174221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=174221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}