{"id":17447,"date":"2013-02-08T22:00:00","date_gmt":"2013-02-08T21:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=17447"},"modified":"2023-01-17T13:15:26","modified_gmt":"2023-01-17T12:15:26","slug":"6178-9-2-gianfranco-fini-a-crotone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6178-9-2-gianfranco-fini-a-crotone\/","title":{"rendered":"Gianfranco Fini a Crotone"},"content":{"rendered":"<p>CROTONE &#8211;&nbsp;Il Presidente della Camera dei Deputati, Gianfranco Fini, oggi sara&#8217; a Crotone.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Alle ore 11.30, nella sala &#8220;Lagani&#8221; dell&#8217;Ance (Associazione Nazionale Costruttori Edili) a Poggio Verde, incontrera&#8217; gli operatori economici della Provincia di Crotone. Nel corso dell&#8217;incontro saranno trattati i temi dell&#8217;occupazione, dell&#8217;ambiente e del territorio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211;&nbsp;Il Presidente della Camera dei Deputati, Gianfranco Fini, oggi sara&#8217; a Crotone.<\/p>\n","protected":false},"author":22,"featured_media":17448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-17447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=17447"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17447\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/17448"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=17447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=17447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=17447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}